{"id":883,"date":"2023-11-03T18:06:47","date_gmt":"2023-11-03T21:06:47","guid":{"rendered":"https:\/\/ajustica.net\/?p=883"},"modified":"2023-11-03T18:08:06","modified_gmt":"2023-11-03T21:08:06","slug":"terminal-de-carga-do-aeroporto-dr-antonio-agostinho-neto-tem-um-edificio-para-cargas-especiais","status":"publish","type":"post","link":"https:\/\/ajustica.net\/index.php\/2023\/11\/03\/terminal-de-carga-do-aeroporto-dr-antonio-agostinho-neto-tem-um-edificio-para-cargas-especiais\/","title":{"rendered":"TERMINAL DE CARGA DO AEROPORTO DR. ANT\u00d3NIO AGOSTINHO NETO TEM UM EDIF\u00cdCIO PARA CARGAS ESPECIAIS"},"content":{"rendered":"\n<p>Ultimam-se os preparativos para a inaugura\u00e7\u00e3o do novo Aeroporto Internacional de Luanda \u2013 Dr. Ant\u00f3nio Agostinho Neto. O corte da fita vai acontecer na sexta-feira, 10 de novembro.<\/p>\n\n\n\n<p>POR: A JUSTI\u00c7A<\/p>\n\n\n\n<p>Numa primeira fase, o novo Aeroporto vai come\u00e7ar a operar com o terminal de carga, uma infra-estrutura com v\u00e1rios servi\u00e7os associados.<\/p>\n\n\n\n<p>Jos\u00e9 Paulo N\u00f3brega, Coordenador do Gabinete Operacional do Aeroporto Internacional de Luanda, diz que o terminal de carga ter\u00e1 a capacidade para receber 130 mil toneladas\/ano, e poder\u00e1 chegar \u00e0s mais de 400 mil se forem feitos mais investimentos.<\/p>\n\n\n\n<p>Jos\u00e9 Paulo N\u00f3brega&nbsp;diz ainda que, o terminal de carga&nbsp;do Aeroporto&nbsp;Dr. Ant\u00f3nio Agostinho Neto, tem bancos, tem tamb\u00e9m duas unidades onde se pode levantar os corpos das pessoas quando falecem no exterior ou no interior e tanto de vir digamos, fundamentalmente, entrada dom\u00e9stica, sa\u00edda internacional, entrada internacional. Aqui temos tamb\u00e9m um edif\u00edcio para cargas especiais. Os avi\u00f5es encostam, descarregam para aqui diretamente e temos aqui todas estas instala\u00e7\u00f5es para as pessoas estarem \u00e0 espera e \u00e9 menos confuso do que aquilo que \u00e9 o aeroporto quarto&nbsp;de fevereiro.<\/p>\n\n\n\n<p>Governo assegura mobilidade ao novo aeroporto internacional<\/p>\n\n\n\n<p>O Instituto Nacional de Estradas (INEA) assegurou, estarem criadas as condi\u00e7\u00f5es para a mobilidade dos acessos ao novo Aeroporto Internacional de Luanda &#8220;Dr Ant\u00f3nio Agostinho Neto&#8221;, cuja inaugura\u00e7\u00e3o est\u00e1 marcada para 10 de Novembro.<\/p>\n\n\n\n<p>De acordo com a directora provincial do INEA, Ros\u00e1ria Kiala, o Executivo trabalha na melhoria da mobilidade atrav\u00e9s da reabilita\u00e7\u00e3o da Avenida Deolinda Rodrigues, da Via Expressa, sentido Cabo Lombo, at\u00e9 a ponte do 25.<\/p>\n\n\n\n<p>Entre as benfeitorias est\u00e1 a melhoria do tapete alf\u00e1ltico, sinaliza\u00e7\u00e3o vertical e horizontal, constru\u00e7\u00e3o de paragens para transportes p\u00fablicos, reabilita\u00e7\u00e3o e constru\u00e7\u00e3o de novas pedonais.<\/p>\n\n\n\n<p>Em declara\u00e7\u00f5es \u00e0 imprensa, no final de uma visita guiada \u00e0s v\u00e1rias infra-estruturas impulsionadas pela constru\u00e7\u00e3o do Novo Aeroporto Internacional de Luanda, Rosa Kila disse est\u00e3o ainda a ser reabilitadas, nesta primeira fase, as avenidas Kima Kienda (Boavista) no distrito urbano da Ingombota, munic\u00edpio de Luanda, a 21 de Janeiro, a Pedro de Castro Van-D\u00fanem Loy, as vias do Patriota e do Futungo.<\/p>\n\n\n\n<p>Ap\u00f3s a conclus\u00e3o das obras, adiantou, a via Expressa ter\u00e1 tr\u00eas faixas de rodagem (actualmente tem duas), sendo que a parte central estar\u00e1 reservada para a constru\u00e7\u00e3o do metro de superf\u00edcie.<\/p>\n\n\n\n<p>&#8220;J\u00e1 temos muito trabalho feito, quem passa, por exemplo, pela Deolinda Rodrigues, consegue notar um antes e depois&#8221;, expressou.<\/p>\n\n\n\n<p>Rosa Kiala fez saber que os trabalhos na Avenida Rodrigues est\u00e3o com uma execu\u00e7\u00e3o de 95 por cento, faltando apenas a coloca\u00e7\u00e3o das novas pedonais, num total de sete.<\/p>\n\n\n\n<p>Na Avenida Fidel Castro, segundo a fonte, ser\u00e3o tamb\u00e9m erguidas oito novas pedonais e, em outras art\u00e9rias de Luanda, est\u00e3o previstas a reabilita\u00e7\u00e3o de mais de 20 pedonais.<\/p>\n\n\n\n<p>Entre as pedonais a reabilitar, Rosa Kiala destacou a do Viaduto do Zango e do Alimenta Angola, em Viana, bem como a pedonal da zona do antigo controlo do Benfica.<\/p>\n\n\n\n<p>Em rela\u00e7\u00e3o a ponte do 25, adiantou que as obras est\u00e3o a 98 por cento de execu\u00e7\u00e3o.<\/p>\n\n\n\n<p>Nesse local foi erguido um viaduto com 70,80 m de extens\u00e3o, duas faixas de rodagem de 3,5 m de largura em cada lado, berma de 1,40 m de largura em cada sentido.<\/p>\n\n\n\n<p>Foi tamb\u00e9m feito um n\u00f3 de liga\u00e7\u00e3o directo \u00e0 EN 230 sentido Catete-Viana, rampas 1,2 e 3 com 525 m de extens\u00e3o, 812 e 384 m de extens\u00e3o, respectivamente, um loop com 237 m de extens\u00e3o, bem como uma rua de cruzamento com 1108 m de extens\u00e3o<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Ultimam-se os preparativos para a inaugura\u00e7\u00e3o do novo Aeroporto Internacional de Luanda \u2013 Dr. Ant\u00f3nio Agostinho Neto. O corte da fita vai acontecer na sexta-feira, 10 de novembro. POR: A JUSTI\u00c7A Numa primeira fase, o novo Aeroporto vai come\u00e7ar a operar com o terminal de carga, uma infra-estrutura com v\u00e1rios servi\u00e7os associados. Jos\u00e9 Paulo N\u00f3brega, [&hellip;]<\/p>\n","protected":false},"author":3,"featured_media":884,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[4],"tags":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v20.10 - https:\/\/yoast.com\/wordpress\/plugins\/seo\/ -->\n<title>TERMINAL DE CARGA DO AEROPORTO DR. ANT\u00d3NIO AGOSTINHO NETO TEM UM EDIF\u00cdCIO PARA CARGAS ESPECIAIS -<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/ajustica.net\/index.php\/2023\/11\/03\/terminal-de-carga-do-aeroporto-dr-antonio-agostinho-neto-tem-um-edificio-para-cargas-especiais\/\" \/>\n<meta property=\"og:locale\" content=\"pt_BR\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"TERMINAL DE CARGA DO AEROPORTO DR. ANT\u00d3NIO AGOSTINHO NETO TEM UM EDIF\u00cdCIO PARA CARGAS ESPECIAIS -\" \/>\n<meta property=\"og:description\" content=\"Ultimam-se os preparativos para a inaugura\u00e7\u00e3o do novo Aeroporto Internacional de Luanda \u2013 Dr. Ant\u00f3nio Agostinho Neto. O corte da fita vai acontecer na sexta-feira, 10 de novembro. POR: A JUSTI\u00c7A Numa primeira fase, o novo Aeroporto vai come\u00e7ar a operar com o terminal de carga, uma infra-estrutura com v\u00e1rios servi\u00e7os associados. Jos\u00e9 Paulo N\u00f3brega, [&hellip;]\" \/>\n<meta property=\"og:url\" content=\"https:\/\/ajustica.net\/index.php\/2023\/11\/03\/terminal-de-carga-do-aeroporto-dr-antonio-agostinho-neto-tem-um-edificio-para-cargas-especiais\/\" \/>\n<meta property=\"article:published_time\" content=\"2023-11-03T21:06:47+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2023-11-03T21:08:06+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/ajustica.net\/wp-content\/uploads\/2023\/11\/ferrovia_LDA.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"700\" \/>\n\t<meta property=\"og:image:height\" content=\"450\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"author\" content=\"Portal Justi\u00e7a\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Escrito por\" \/>\n\t<meta name=\"twitter:data1\" content=\"Portal Justi\u00e7a\" \/>\n\t<meta name=\"twitter:label2\" content=\"Est. tempo de leitura\" \/>\n\t<meta name=\"twitter:data2\" content=\"4 minutos\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\/\/schema.org\",\"@graph\":[{\"@type\":\"WebPage\",\"@id\":\"https:\/\/ajustica.net\/index.php\/2023\/11\/03\/terminal-de-carga-do-aeroporto-dr-antonio-agostinho-neto-tem-um-edificio-para-cargas-especiais\/\",\"url\":\"https:\/\/ajustica.net\/index.php\/2023\/11\/03\/terminal-de-carga-do-aeroporto-dr-antonio-agostinho-neto-tem-um-edificio-para-cargas-especiais\/\",\"name\":\"TERMINAL DE CARGA DO AEROPORTO DR. ANT\u00d3NIO AGOSTINHO NETO TEM UM EDIF\u00cdCIO PARA CARGAS ESPECIAIS -\",\"isPartOf\":{\"@id\":\"https:\/\/ajustica.net\/#website\"},\"datePublished\":\"2023-11-03T21:06:47+00:00\",\"dateModified\":\"2023-11-03T21:08:06+00:00\",\"author\":{\"@id\":\"https:\/\/ajustica.net\/#\/schema\/person\/e1f71ed49e0f63898db2951a6b747d62\"},\"breadcrumb\":{\"@id\":\"https:\/\/ajustica.net\/index.php\/2023\/11\/03\/terminal-de-carga-do-aeroporto-dr-antonio-agostinho-neto-tem-um-edificio-para-cargas-especiais\/#breadcrumb\"},\"inLanguage\":\"pt-BR\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\/\/ajustica.net\/index.php\/2023\/11\/03\/terminal-de-carga-do-aeroporto-dr-antonio-agostinho-neto-tem-um-edificio-para-cargas-especiais\/\"]}]},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\/\/ajustica.net\/index.php\/2023\/11\/03\/terminal-de-carga-do-aeroporto-dr-antonio-agostinho-neto-tem-um-edificio-para-cargas-especiais\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"In\u00edcio\",\"item\":\"https:\/\/ajustica.net\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"TERMINAL DE CARGA DO AEROPORTO DR. ANT\u00d3NIO AGOSTINHO NETO TEM UM EDIF\u00cdCIO PARA CARGAS ESPECIAIS\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\/\/ajustica.net\/#website\",\"url\":\"https:\/\/ajustica.net\/\",\"name\":\"\",\"description\":\"Email Para Den\u00fancia: ajusticaa@gmail.com\",\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\/\/ajustica.net\/?s={search_term_string}\"},\"query-input\":\"required name=search_term_string\"}],\"inLanguage\":\"pt-BR\"},{\"@type\":\"Person\",\"@id\":\"https:\/\/ajustica.net\/#\/schema\/person\/e1f71ed49e0f63898db2951a6b747d62\",\"name\":\"Portal Justi\u00e7a\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"pt-BR\",\"@id\":\"https:\/\/ajustica.net\/#\/schema\/person\/image\/\",\"url\":\"https:\/\/secure.gravatar.com\/avatar\/14c19bb3bbce6a73ddabbf74322a5807?s=96&d=mm&r=g\",\"contentUrl\":\"https:\/\/secure.gravatar.com\/avatar\/14c19bb3bbce6a73ddabbf74322a5807?s=96&d=mm&r=g\",\"caption\":\"Portal Justi\u00e7a\"},\"url\":\"https:\/\/ajustica.net\/index.php\/author\/justica\/\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"TERMINAL DE CARGA DO AEROPORTO DR. ANT\u00d3NIO AGOSTINHO NETO TEM UM EDIF\u00cdCIO PARA CARGAS ESPECIAIS -","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/ajustica.net\/index.php\/2023\/11\/03\/terminal-de-carga-do-aeroporto-dr-antonio-agostinho-neto-tem-um-edificio-para-cargas-especiais\/","og_locale":"pt_BR","og_type":"article","og_title":"TERMINAL DE CARGA DO AEROPORTO DR. ANT\u00d3NIO AGOSTINHO NETO TEM UM EDIF\u00cdCIO PARA CARGAS ESPECIAIS -","og_description":"Ultimam-se os preparativos para a inaugura\u00e7\u00e3o do novo Aeroporto Internacional de Luanda \u2013 Dr. Ant\u00f3nio Agostinho Neto. O corte da fita vai acontecer na sexta-feira, 10 de novembro. POR: A JUSTI\u00c7A Numa primeira fase, o novo Aeroporto vai come\u00e7ar a operar com o terminal de carga, uma infra-estrutura com v\u00e1rios servi\u00e7os associados. Jos\u00e9 Paulo N\u00f3brega, [&hellip;]","og_url":"https:\/\/ajustica.net\/index.php\/2023\/11\/03\/terminal-de-carga-do-aeroporto-dr-antonio-agostinho-neto-tem-um-edificio-para-cargas-especiais\/","article_published_time":"2023-11-03T21:06:47+00:00","article_modified_time":"2023-11-03T21:08:06+00:00","og_image":[{"width":700,"height":450,"url":"https:\/\/ajustica.net\/wp-content\/uploads\/2023\/11\/ferrovia_LDA.jpg","type":"image\/jpeg"}],"author":"Portal Justi\u00e7a","twitter_card":"summary_large_image","twitter_misc":{"Escrito por":"Portal Justi\u00e7a","Est. tempo de leitura":"4 minutos"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"WebPage","@id":"https:\/\/ajustica.net\/index.php\/2023\/11\/03\/terminal-de-carga-do-aeroporto-dr-antonio-agostinho-neto-tem-um-edificio-para-cargas-especiais\/","url":"https:\/\/ajustica.net\/index.php\/2023\/11\/03\/terminal-de-carga-do-aeroporto-dr-antonio-agostinho-neto-tem-um-edificio-para-cargas-especiais\/","name":"TERMINAL DE CARGA DO AEROPORTO DR. ANT\u00d3NIO AGOSTINHO NETO TEM UM EDIF\u00cdCIO PARA CARGAS ESPECIAIS -","isPartOf":{"@id":"https:\/\/ajustica.net\/#website"},"datePublished":"2023-11-03T21:06:47+00:00","dateModified":"2023-11-03T21:08:06+00:00","author":{"@id":"https:\/\/ajustica.net\/#\/schema\/person\/e1f71ed49e0f63898db2951a6b747d62"},"breadcrumb":{"@id":"https:\/\/ajustica.net\/index.php\/2023\/11\/03\/terminal-de-carga-do-aeroporto-dr-antonio-agostinho-neto-tem-um-edificio-para-cargas-especiais\/#breadcrumb"},"inLanguage":"pt-BR","potentialAction":[{"@type":"ReadAction","target":["https:\/\/ajustica.net\/index.php\/2023\/11\/03\/terminal-de-carga-do-aeroporto-dr-antonio-agostinho-neto-tem-um-edificio-para-cargas-especiais\/"]}]},{"@type":"BreadcrumbList","@id":"https:\/\/ajustica.net\/index.php\/2023\/11\/03\/terminal-de-carga-do-aeroporto-dr-antonio-agostinho-neto-tem-um-edificio-para-cargas-especiais\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"In\u00edcio","item":"https:\/\/ajustica.net\/"},{"@type":"ListItem","position":2,"name":"TERMINAL DE CARGA DO AEROPORTO DR. ANT\u00d3NIO AGOSTINHO NETO TEM UM EDIF\u00cdCIO PARA CARGAS ESPECIAIS"}]},{"@type":"WebSite","@id":"https:\/\/ajustica.net\/#website","url":"https:\/\/ajustica.net\/","name":"","description":"Email Para Den\u00fancia: ajusticaa@gmail.com","potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/ajustica.net\/?s={search_term_string}"},"query-input":"required name=search_term_string"}],"inLanguage":"pt-BR"},{"@type":"Person","@id":"https:\/\/ajustica.net\/#\/schema\/person\/e1f71ed49e0f63898db2951a6b747d62","name":"Portal Justi\u00e7a","image":{"@type":"ImageObject","inLanguage":"pt-BR","@id":"https:\/\/ajustica.net\/#\/schema\/person\/image\/","url":"https:\/\/secure.gravatar.com\/avatar\/14c19bb3bbce6a73ddabbf74322a5807?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/14c19bb3bbce6a73ddabbf74322a5807?s=96&d=mm&r=g","caption":"Portal Justi\u00e7a"},"url":"https:\/\/ajustica.net\/index.php\/author\/justica\/"}]}},"_links":{"self":[{"href":"https:\/\/ajustica.net\/index.php\/wp-json\/wp\/v2\/posts\/883"}],"collection":[{"href":"https:\/\/ajustica.net\/index.php\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/ajustica.net\/index.php\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/ajustica.net\/index.php\/wp-json\/wp\/v2\/users\/3"}],"replies":[{"embeddable":true,"href":"https:\/\/ajustica.net\/index.php\/wp-json\/wp\/v2\/comments?post=883"}],"version-history":[{"count":1,"href":"https:\/\/ajustica.net\/index.php\/wp-json\/wp\/v2\/posts\/883\/revisions"}],"predecessor-version":[{"id":885,"href":"https:\/\/ajustica.net\/index.php\/wp-json\/wp\/v2\/posts\/883\/revisions\/885"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/ajustica.net\/index.php\/wp-json\/wp\/v2\/media\/884"}],"wp:attachment":[{"href":"https:\/\/ajustica.net\/index.php\/wp-json\/wp\/v2\/media?parent=883"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/ajustica.net\/index.php\/wp-json\/wp\/v2\/categories?post=883"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/ajustica.net\/index.php\/wp-json\/wp\/v2\/tags?post=883"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}