{"id":4481,"date":"2026-01-08T18:36:15","date_gmt":"2026-01-08T21:36:15","guid":{"rendered":"https:\/\/ajustica.net\/?p=4481"},"modified":"2026-01-08T18:36:16","modified_gmt":"2026-01-08T21:36:16","slug":"libertado-vice-presidente-de-associacao-dos-taxistas-acusado-de-terrorismo","status":"publish","type":"post","link":"https:\/\/ajustica.net\/index.php\/2026\/01\/08\/libertado-vice-presidente-de-associacao-dos-taxistas-acusado-de-terrorismo\/","title":{"rendered":"LIBERTADO VICE-PRESIDENTE DE ASSOCIA\u00c7\u00c3O DOS TAXISTAS ACUSADO DE TERRORISMO"},"content":{"rendered":"\n<p>O vice-presidente da Associa\u00e7\u00e3o Nacional dos Taxistas de Angola (ANA\u03a4\u0391), acusado de terrorismo ap\u00f3s a greve de transportes de julho de 2025, foi libertado e viu o processo arquivado, disse hoje \u00e0 Lusa o seu advogado.<\/p>\n\n\n\n<p>Rodrigo Luciano Catimba estava detido desde agosto de 2025, acusado pela Procuradoria-Geral da Rep\u00fablica de crimes que inclu\u00edam terrorismo, associa\u00e7\u00e3o criminosa, instiga\u00e7\u00e3o p\u00fablica ao crime, participa\u00e7\u00e3o em motim, atentado contra a seguran\u00e7a dos transportes e promo\u00e7\u00e3o de vandalismo, no contexto da greve dos taxistas que resultou em motins e v\u00e1rias mortes em Luanda.<\/p>\n\n\n\n<p>O mandado de soltura, datado de 05 de janeiro, indica que os autos foram arquivados, sem continua\u00e7\u00e3o do processo penal. Uma decis\u00e3o que para a defesa confirma que n\u00e3o existiam provas suficientes para manter a acusa\u00e7\u00e3o.<\/p>\n\n\n\n<p>&#8220;O arquivamento significa claramente que houve, no in\u00edcio, enormes excessos e uma abordagem completamente disparatada por parte das autoridades&#8221;, afirmou \u00e0 Lusa o advogado Francisco Muteka.<\/p>\n\n\n\n<p>Muteka anunciou que vai avan\u00e7ar com um processo judicial contra o Estado angolano, visando obter responsabiliza\u00e7\u00e3o por cada noite que o seu constituinte passou na cadeia e pelos preju\u00edzos causados \u00e0 sua imagem e reputa\u00e7\u00e3o.<\/p>\n\n\n\n<p>A greve dos taxistas convocada pela ANATA e outras associa\u00e7\u00f5es entre 28 e 30 de julho de 2025 tinha como objetivo contestar o aumento do pre\u00e7o dos combust\u00edveis, mas rapidamente evoluiu para dist\u00farbios, atos de vandalismo e pilhagens.<\/p>\n\n\n\n<p>No final, cerca de 30 pessoas morreram, mais de 200 ficaram feridas e mais de 1.200 foram detidas, incluindo oito dirigentes de associa\u00e7\u00f5es de taxistas e mototaxistas, suscitando cr\u00edticas de organiza\u00e7\u00f5es dos direitos humanos face \u00e0 rea\u00e7\u00e3o das autoridades angolanas.<\/p>\n\n\n\n<p>Segundo Francisco Muteka, todos estar\u00e3o j\u00e1 livres ou prestes a serem libertados.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>O vice-presidente da Associa\u00e7\u00e3o Nacional dos Taxistas de Angola (ANA\u03a4\u0391), acusado de terrorismo ap\u00f3s a greve de transportes de julho de 2025, foi libertado e viu o processo arquivado, disse hoje \u00e0 Lusa o seu advogado. Rodrigo Luciano Catimba estava detido desde agosto de 2025, acusado pela Procuradoria-Geral da Rep\u00fablica de crimes que inclu\u00edam terrorismo, [&hellip;]<\/p>\n","protected":false},"author":3,"featured_media":4482,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[2,1],"tags":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v20.10 - https:\/\/yoast.com\/wordpress\/plugins\/seo\/ -->\n<title>LIBERTADO VICE-PRESIDENTE DE ASSOCIA\u00c7\u00c3O DOS TAXISTAS ACUSADO DE TERRORISMO -<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/ajustica.net\/index.php\/2026\/01\/08\/libertado-vice-presidente-de-associacao-dos-taxistas-acusado-de-terrorismo\/\" \/>\n<meta property=\"og:locale\" content=\"pt_BR\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"LIBERTADO VICE-PRESIDENTE DE ASSOCIA\u00c7\u00c3O DOS TAXISTAS ACUSADO DE TERRORISMO -\" \/>\n<meta property=\"og:description\" content=\"O vice-presidente da Associa\u00e7\u00e3o Nacional dos Taxistas de Angola (ANA\u03a4\u0391), acusado de terrorismo ap\u00f3s a greve de transportes de julho de 2025, foi libertado e viu o processo arquivado, disse hoje \u00e0 Lusa o seu advogado. Rodrigo Luciano Catimba estava detido desde agosto de 2025, acusado pela Procuradoria-Geral da Rep\u00fablica de crimes que inclu\u00edam terrorismo, [&hellip;]\" \/>\n<meta property=\"og:url\" content=\"https:\/\/ajustica.net\/index.php\/2026\/01\/08\/libertado-vice-presidente-de-associacao-dos-taxistas-acusado-de-terrorismo\/\" \/>\n<meta property=\"article:published_time\" content=\"2026-01-08T21:36:15+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2026-01-08T21:36:16+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/ajustica.net\/wp-content\/uploads\/2026\/01\/6bdad059916571d7049a68f0fe96bf1e_L.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"700\" \/>\n\t<meta property=\"og:image:height\" content=\"467\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"author\" content=\"Portal Justi\u00e7a\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Escrito por\" \/>\n\t<meta name=\"twitter:data1\" content=\"Portal Justi\u00e7a\" \/>\n\t<meta name=\"twitter:label2\" content=\"Est. tempo de leitura\" \/>\n\t<meta name=\"twitter:data2\" content=\"2 minutos\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\/\/schema.org\",\"@graph\":[{\"@type\":\"WebPage\",\"@id\":\"https:\/\/ajustica.net\/index.php\/2026\/01\/08\/libertado-vice-presidente-de-associacao-dos-taxistas-acusado-de-terrorismo\/\",\"url\":\"https:\/\/ajustica.net\/index.php\/2026\/01\/08\/libertado-vice-presidente-de-associacao-dos-taxistas-acusado-de-terrorismo\/\",\"name\":\"LIBERTADO VICE-PRESIDENTE DE ASSOCIA\u00c7\u00c3O DOS TAXISTAS ACUSADO DE TERRORISMO -\",\"isPartOf\":{\"@id\":\"https:\/\/ajustica.net\/#website\"},\"datePublished\":\"2026-01-08T21:36:15+00:00\",\"dateModified\":\"2026-01-08T21:36:16+00:00\",\"author\":{\"@id\":\"https:\/\/ajustica.net\/#\/schema\/person\/e1f71ed49e0f63898db2951a6b747d62\"},\"breadcrumb\":{\"@id\":\"https:\/\/ajustica.net\/index.php\/2026\/01\/08\/libertado-vice-presidente-de-associacao-dos-taxistas-acusado-de-terrorismo\/#breadcrumb\"},\"inLanguage\":\"pt-BR\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\/\/ajustica.net\/index.php\/2026\/01\/08\/libertado-vice-presidente-de-associacao-dos-taxistas-acusado-de-terrorismo\/\"]}]},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\/\/ajustica.net\/index.php\/2026\/01\/08\/libertado-vice-presidente-de-associacao-dos-taxistas-acusado-de-terrorismo\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"In\u00edcio\",\"item\":\"https:\/\/ajustica.net\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"LIBERTADO VICE-PRESIDENTE DE ASSOCIA\u00c7\u00c3O DOS TAXISTAS ACUSADO DE TERRORISMO\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\/\/ajustica.net\/#website\",\"url\":\"https:\/\/ajustica.net\/\",\"name\":\"\",\"description\":\"Email Para Den\u00fancia: ajusticaa@gmail.com\",\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\/\/ajustica.net\/?s={search_term_string}\"},\"query-input\":\"required name=search_term_string\"}],\"inLanguage\":\"pt-BR\"},{\"@type\":\"Person\",\"@id\":\"https:\/\/ajustica.net\/#\/schema\/person\/e1f71ed49e0f63898db2951a6b747d62\",\"name\":\"Portal Justi\u00e7a\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"pt-BR\",\"@id\":\"https:\/\/ajustica.net\/#\/schema\/person\/image\/\",\"url\":\"https:\/\/secure.gravatar.com\/avatar\/14c19bb3bbce6a73ddabbf74322a5807?s=96&d=mm&r=g\",\"contentUrl\":\"https:\/\/secure.gravatar.com\/avatar\/14c19bb3bbce6a73ddabbf74322a5807?s=96&d=mm&r=g\",\"caption\":\"Portal Justi\u00e7a\"},\"url\":\"https:\/\/ajustica.net\/index.php\/author\/justica\/\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"LIBERTADO VICE-PRESIDENTE DE ASSOCIA\u00c7\u00c3O DOS TAXISTAS ACUSADO DE TERRORISMO -","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/ajustica.net\/index.php\/2026\/01\/08\/libertado-vice-presidente-de-associacao-dos-taxistas-acusado-de-terrorismo\/","og_locale":"pt_BR","og_type":"article","og_title":"LIBERTADO VICE-PRESIDENTE DE ASSOCIA\u00c7\u00c3O DOS TAXISTAS ACUSADO DE TERRORISMO -","og_description":"O vice-presidente da Associa\u00e7\u00e3o Nacional dos Taxistas de Angola (ANA\u03a4\u0391), acusado de terrorismo ap\u00f3s a greve de transportes de julho de 2025, foi libertado e viu o processo arquivado, disse hoje \u00e0 Lusa o seu advogado. Rodrigo Luciano Catimba estava detido desde agosto de 2025, acusado pela Procuradoria-Geral da Rep\u00fablica de crimes que inclu\u00edam terrorismo, [&hellip;]","og_url":"https:\/\/ajustica.net\/index.php\/2026\/01\/08\/libertado-vice-presidente-de-associacao-dos-taxistas-acusado-de-terrorismo\/","article_published_time":"2026-01-08T21:36:15+00:00","article_modified_time":"2026-01-08T21:36:16+00:00","og_image":[{"width":700,"height":467,"url":"https:\/\/ajustica.net\/wp-content\/uploads\/2026\/01\/6bdad059916571d7049a68f0fe96bf1e_L.jpg","type":"image\/jpeg"}],"author":"Portal Justi\u00e7a","twitter_card":"summary_large_image","twitter_misc":{"Escrito por":"Portal Justi\u00e7a","Est. tempo de leitura":"2 minutos"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"WebPage","@id":"https:\/\/ajustica.net\/index.php\/2026\/01\/08\/libertado-vice-presidente-de-associacao-dos-taxistas-acusado-de-terrorismo\/","url":"https:\/\/ajustica.net\/index.php\/2026\/01\/08\/libertado-vice-presidente-de-associacao-dos-taxistas-acusado-de-terrorismo\/","name":"LIBERTADO VICE-PRESIDENTE DE ASSOCIA\u00c7\u00c3O DOS TAXISTAS ACUSADO DE TERRORISMO -","isPartOf":{"@id":"https:\/\/ajustica.net\/#website"},"datePublished":"2026-01-08T21:36:15+00:00","dateModified":"2026-01-08T21:36:16+00:00","author":{"@id":"https:\/\/ajustica.net\/#\/schema\/person\/e1f71ed49e0f63898db2951a6b747d62"},"breadcrumb":{"@id":"https:\/\/ajustica.net\/index.php\/2026\/01\/08\/libertado-vice-presidente-de-associacao-dos-taxistas-acusado-de-terrorismo\/#breadcrumb"},"inLanguage":"pt-BR","potentialAction":[{"@type":"ReadAction","target":["https:\/\/ajustica.net\/index.php\/2026\/01\/08\/libertado-vice-presidente-de-associacao-dos-taxistas-acusado-de-terrorismo\/"]}]},{"@type":"BreadcrumbList","@id":"https:\/\/ajustica.net\/index.php\/2026\/01\/08\/libertado-vice-presidente-de-associacao-dos-taxistas-acusado-de-terrorismo\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"In\u00edcio","item":"https:\/\/ajustica.net\/"},{"@type":"ListItem","position":2,"name":"LIBERTADO VICE-PRESIDENTE DE ASSOCIA\u00c7\u00c3O DOS TAXISTAS ACUSADO DE TERRORISMO"}]},{"@type":"WebSite","@id":"https:\/\/ajustica.net\/#website","url":"https:\/\/ajustica.net\/","name":"","description":"Email Para Den\u00fancia: ajusticaa@gmail.com","potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/ajustica.net\/?s={search_term_string}"},"query-input":"required name=search_term_string"}],"inLanguage":"pt-BR"},{"@type":"Person","@id":"https:\/\/ajustica.net\/#\/schema\/person\/e1f71ed49e0f63898db2951a6b747d62","name":"Portal Justi\u00e7a","image":{"@type":"ImageObject","inLanguage":"pt-BR","@id":"https:\/\/ajustica.net\/#\/schema\/person\/image\/","url":"https:\/\/secure.gravatar.com\/avatar\/14c19bb3bbce6a73ddabbf74322a5807?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/14c19bb3bbce6a73ddabbf74322a5807?s=96&d=mm&r=g","caption":"Portal Justi\u00e7a"},"url":"https:\/\/ajustica.net\/index.php\/author\/justica\/"}]}},"_links":{"self":[{"href":"https:\/\/ajustica.net\/index.php\/wp-json\/wp\/v2\/posts\/4481"}],"collection":[{"href":"https:\/\/ajustica.net\/index.php\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/ajustica.net\/index.php\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/ajustica.net\/index.php\/wp-json\/wp\/v2\/users\/3"}],"replies":[{"embeddable":true,"href":"https:\/\/ajustica.net\/index.php\/wp-json\/wp\/v2\/comments?post=4481"}],"version-history":[{"count":1,"href":"https:\/\/ajustica.net\/index.php\/wp-json\/wp\/v2\/posts\/4481\/revisions"}],"predecessor-version":[{"id":4483,"href":"https:\/\/ajustica.net\/index.php\/wp-json\/wp\/v2\/posts\/4481\/revisions\/4483"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/ajustica.net\/index.php\/wp-json\/wp\/v2\/media\/4482"}],"wp:attachment":[{"href":"https:\/\/ajustica.net\/index.php\/wp-json\/wp\/v2\/media?parent=4481"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/ajustica.net\/index.php\/wp-json\/wp\/v2\/categories?post=4481"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/ajustica.net\/index.php\/wp-json\/wp\/v2\/tags?post=4481"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}