{"id":3538,"date":"2025-06-27T06:00:56","date_gmt":"2025-06-27T09:00:56","guid":{"rendered":"https:\/\/ajustica.net\/?p=3538"},"modified":"2025-06-27T06:00:57","modified_gmt":"2025-06-27T09:00:57","slug":"banco-sol-pce-osvaldo-macaia-o-protegido-diz-e-faz-conforme-lhe-apetece","status":"publish","type":"post","link":"https:\/\/ajustica.net\/index.php\/2025\/06\/27\/banco-sol-pce-osvaldo-macaia-o-protegido-diz-e-faz-conforme-lhe-apetece\/","title":{"rendered":"BANCO SOL: PCE OSVALDO MACAIA O PROTEGIDO DIZ E FAZ CONFORME LHE APETECE"},"content":{"rendered":"\n<p>Em Abril de 2024 quando Osvaldo Macaia assumiu o cargo de PCE do Banco Sol supostamente logo a seguir havia feito um diagn\u00f3stico relatando as condi\u00e7\u00f5es em que encontrou a institui\u00e7\u00e3o, sugerindo dentre as ac\u00e7\u00f5es correctivas a diminui\u00e7\u00e3o dos custos e renegocia\u00e7\u00e3o de contratos em vigor na altura, verdade \u00e9 que quase ou nada foi feito neste sentido, permanecem os mesmos v\u00edcios e m\u00e1s pr\u00e1ticas da Comiss\u00e3o Executiva anterior, continuam as facturas sobrefaturadas, permanecem os contratos com as mesmas prestadoras de servi\u00e7os e inclusive mant\u00e9m no seu elenco at\u00e9 Bernardo Panzo, chefe de Departamento da DTI um dos maiores ladr\u00f5es tal como Gil Benchimol PCA da Sol Seguros, que mesmo estando fora de Angola por mais de um ano sem justifica\u00e7\u00e3o alguma continua a receber os seus sal\u00e1rios, tudo isto confirma que as mesmas pr\u00e1ticas lesivas prevalecem.<\/p>\n\n\n\n<p>Na mesma altura alegou que havia excedente de pessoal a verdade \u00e9 que desde que Macaia est\u00e1 no comando j\u00e1 trouxe consigo mais de 200 pessoas (dos quais cerca de mais de 65% j\u00e1 receberam cr\u00e9ditos avultados, sem sequer completarem um ano de servi\u00e7o e nem cumprimento de alguns dos outros requisitos necess\u00e1rios para o efeito), todas estas com sal\u00e1rios superiores aos colaboradores s\u00e9niores com mais de 20 anos de casa, t\u00e9cnicos rdos novos rec\u00e9m enquadrados a ufruirem sal\u00e1rios superiores gerentes de balc\u00f5es, a alguns chefes de departamento e at\u00e9 directores, na mesma senda criou novos departamentos e direc\u00e7\u00f5es para acomodar os seus, real\u00e7ar que alguns entraram j\u00e1 depois do aviso do BNA de 25 Abril de 2025, como \u00e9 o caso de pessoas pr\u00f3ximas a Esteves Hil\u00e1rio e Tito Cambanje, dentre elas parentes, namoradas e amigos.<\/p>\n\n\n\n<p>Tito Cambanje nas vestes de Assessor e o pr\u00f3prio Macaia, s\u00e3o actualmente as pessoas que mandam e determinam inclusive quem deve ou n\u00e3o comprar divisas ou tratar o cart\u00e3o VISA Kumb\u00fa, em detrimento dos verdadeiros clientes, porque estas mesmas pessoas s\u00e3o aquelas que depositam dinheiro somente para as opera\u00e7\u00f5es cambiais contribuindo em nada para a carteira de dep\u00f3sitos, porque o dinheiro entra e sai logo, clientes sem hist\u00f3rico algum no banco e abriram contas especificamente para a aquisi\u00e7\u00e3o de divisas, tal como aconteceu no Banco Yetu os dois acima citados s\u00e3o tamb\u00e9m respons\u00e1veis pela venda de divisas directamente no mercado paralelo do m\u00e1rtires do Kifangondo, directamente ou atrav\u00e9s dos tais elementos que s\u00e3o autorizados a comprar as mesmas.<\/p>\n\n\n\n<p>Existe tamb\u00e9m um conflito entre o PCE e o PCA Andr\u00e9 Lopes, porque ao contr\u00e1rio de Macaia o PCA pauta por uma conduta exemplar fruto dos anos de servi\u00e7o a n\u00edvel da Banca, mas n\u00e3o \u00e9 tido nem achado porque Macaia gaba-se e ama\u00e7a nas reuni\u00f5es do Conselho de Administra\u00e7\u00e3o e Comiss\u00e3o Executiva, nos corredores e inclusive em circulos de amigos, de que n\u00e3o recebe nem ordens do accionista maiorit\u00e1rio (GEFI), mas apenas do Secret\u00e1rio Geral do MPLA Paulo Pombolo a quem entrega semanalmente os envelopes com divisas e vende divisas as empresas ou pessoas que ele indica, emprega as namoradas e at\u00e9 porque n\u00e3o est\u00e1 no Banco Sol por muito tempo, porque o Secret\u00e1rio Geral j\u00e1 o prometeu ascender ao cargo de Governador do BNA.<\/p>\n\n\n\n<p>\u00c9 falsa a no\u00e7\u00e3o de que os accionistas tenham sequer aprovado o Programa de Reestrutura\u00e7\u00e3o e Recapitaliza\u00e7\u00e3o (PRR) e at\u00e9 o BNA, fizeram sim observa\u00e7\u00f5es e correc\u00e7\u00f5es que n\u00e3o foram tidas em conta, isto \u00e9 tudo ideia de Macaia que agora aparece a justificar em comunicados pr\u00e1ticamente dizendo que quem decidiu fechar ag\u00eancias e despedir trabalhadores \u00e9 o BNA ou os accionistas, neste quesito o BNA inclusive coloca d\u00favidas conforme uma reserva na Carta de 25\/04\/25 dirigida ao Banco Sol em que dentre outras diz o seguinte :<\/p>\n\n\n\n<p>\u201c.. Fica sujeito o Banco Sol, S.A. sujeito as seguintes restri\u00e7\u00f5es enquanto durar a implemeta\u00e7\u00e3o do PRR :<\/p>\n\n\n\n<p>1 \u2013 Probi\u00e7\u00e3o da concess\u00e3o de cr\u00e9ditos sem a pr\u00e9via comunica\u00e7\u00e3o ao Banco Nacional de Angola;<\/p>\n\n\n\n<p>2 \u2013 Limita\u00e7\u00e3o de aumentos salariais, concess\u00e3o de b\u00f3nus e outros benef\u00edcios aos colaboradores e membros do \u00f3rg\u00e3o de administra\u00e7\u00e3o\u201d<\/p>\n\n\n\n<p>\u201c.. 4 \u2013 Proibi\u00e7\u00e3o da contrata\u00e7\u00e3o de novos funcion\u00e1rios; e<\/p>\n\n\n\n<p>5 \u2013 Probi\u00e7\u00e3o da aquisi\u00e7\u00e3o de novos servi\u00e7os ou contrata\u00e7\u00e3o de ferramentas sem comunica\u00e7\u00e3o ao Banco Nacional de Angola.\u201d<\/p>\n\n\n\n<p>\u201cEntretanto, o Banco Nacional de Angolamanifesta alguma reserva relativamente a exiquibilidadede algumas medidas de reestrutura\u00e7\u00e3 vertidas no PRR, nomeadamente o volume de capta\u00e7\u00e3o de dep\u00f3sitos, volume de venda de divisas e a magnitude de recupera\u00e7\u00e3o do cr\u00e9dito vencido\u201d.<\/p>\n\n\n\n<p>Assim sendo, verifica-se que nem aos accionistas e nem sequer ao BNA o todo poderoso Macaia obedece tendo, j\u00e1 atropelado e ignorado inclusive os 4 pontos anteriormente citados e instru\u00e7\u00f5es do BNA, tendo inclusive contratado sem necessidade os servi\u00e7os de uma empresa para ver no mercado os futuros administradores da Sol Seguros e outros quadros que ele ainda acha que supostamente s\u00e3o necess\u00e1rios, mesmo tendo sido advertido para n\u00e3o o fazer.<\/p>\n\n\n\n<p>Infelizmente com o fecho dos 39 balc\u00f5es em 10 prov\u00edncias e o envio pra casa de mais de 350 colaboradores, agudiza-se mais ainda a situa\u00e7\u00e3o fruto de uma gest\u00e3o danosa que est\u00e1 mais focada na auto promo\u00e7\u00e3o pessoal de Osvaldo Macaia (a algum tempo chamado de \u201cMacaiabo\u201d pelos funcion\u00e1rios), que somente olha pra o seu umbigo, chegando a exigir inclusive na Assembleia dos Accionistas comiss\u00f5es por cada d\u00edvida que seja paga pelos credores do banco. Estes encerramentos v\u00e3o diminuir a exposi\u00e7\u00e3o comercial, v\u00e3o encher os restantes balc\u00f5es, vai baixar a qualidade e celeridade do servi\u00e7o prestado, v\u00e3o implicar desloca\u00e7\u00f5es dos poss\u00edveis depositantes o que implica perda de clientes e redu\u00e7\u00e3o brusca da carteira de dep\u00f3sitos, isto sem falarmos no valor que ser\u00e1 pago em indemniza\u00e7\u00f5es e a perda de capital humano experiente, possivelmente a cria\u00e7\u00e3o de mais inadiplentes (devedores), porque alguns dos agora despedidos n\u00e3o ter\u00e3o como pagar os cr\u00e9ditos que adquiram para compra de habita\u00e7\u00e3o, carros e outros bens, \u00e9 receio generalizado de quem tenha cr\u00e9dito n\u00e3o receba nenhuma indemniza\u00e7\u00e3o, porque este valor serviria ent\u00e3o para o pagamento das d\u00edvidas e nalguns com alguma ainda pra pagar em fun\u00e7\u00e3o dos valores em mesmo desempregados. Macaia mata assim o sonho de muitos chefes de fam\u00edlia e por consequ\u00eancia dos seus filhos e at\u00e9 netos, porque muitos ter\u00e3o que abandonar as escolas, universidades e inclusive passar fome, isto quando nem deveria ter empregado mais de 200 pessoas, se j\u00e1 sabia que iria despedir outros tantos. H\u00e1 relatos ja de uma morte em consequ\u00eancia dos despedimentos e outros que tmab\u00e9m tiveram AVC nalgumas prov\u00edncias fruto da insensibilidade e p\u00e9ssima gest\u00e3o de Macaia.<\/p>\n\n\n\n<p>O acima exposto implica uma interven\u00e7\u00e3o imediata dos accionistas que n\u00e3o ter\u00e3o dividendos por tr\u00eas anos (enquanto o Macaia recebe a vontade os seus 32 milh\u00f5es por m\u00eas, outras ajudas de custo e ainda vende os d\u00f3lares dele no m\u00e1rtires, dando a impress\u00e3o at\u00e9 de que os accionistas \u00e9 que s\u00e3o o empregados), o MPLA \u00e9 que vai perder militantes, votos e credibilidade porque a bandeira sempre foi gera\u00e7\u00e3o de empregos e n\u00e3o desemprego, o Banco perde a sua reputa\u00e7\u00e3o e est\u00e1 ainda por cima Macaia a colocar em causa at\u00e9 o BNA.<\/p>\n\n\n\n<p>Salvem por favor o Banco Sol das garras do \u201cMacaiabo\u201d porque n\u00e3o haver\u00e1 outro destino sen\u00e3o a fal\u00eancia efectiva e mais desemprego ainda.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Em Abril de 2024 quando Osvaldo Macaia assumiu o cargo de PCE do Banco Sol supostamente logo a seguir havia feito um diagn\u00f3stico relatando as condi\u00e7\u00f5es em que encontrou a institui\u00e7\u00e3o, sugerindo dentre as ac\u00e7\u00f5es correctivas a diminui\u00e7\u00e3o dos custos e renegocia\u00e7\u00e3o de contratos em vigor na altura, verdade \u00e9 que quase ou nada foi [&hellip;]<\/p>\n","protected":false},"author":3,"featured_media":3539,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[2,1],"tags":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v20.10 - https:\/\/yoast.com\/wordpress\/plugins\/seo\/ -->\n<title>BANCO SOL: PCE OSVALDO MACAIA O PROTEGIDO DIZ E FAZ CONFORME LHE APETECE -<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/ajustica.net\/index.php\/2025\/06\/27\/banco-sol-pce-osvaldo-macaia-o-protegido-diz-e-faz-conforme-lhe-apetece\/\" \/>\n<meta property=\"og:locale\" content=\"pt_BR\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"BANCO SOL: PCE OSVALDO MACAIA O PROTEGIDO DIZ E FAZ CONFORME LHE APETECE -\" \/>\n<meta property=\"og:description\" content=\"Em Abril de 2024 quando Osvaldo Macaia assumiu o cargo de PCE do Banco Sol supostamente logo a seguir havia feito um diagn\u00f3stico relatando as condi\u00e7\u00f5es em que encontrou a institui\u00e7\u00e3o, sugerindo dentre as ac\u00e7\u00f5es correctivas a diminui\u00e7\u00e3o dos custos e renegocia\u00e7\u00e3o de contratos em vigor na altura, verdade \u00e9 que quase ou nada foi [&hellip;]\" \/>\n<meta property=\"og:url\" content=\"https:\/\/ajustica.net\/index.php\/2025\/06\/27\/banco-sol-pce-osvaldo-macaia-o-protegido-diz-e-faz-conforme-lhe-apetece\/\" \/>\n<meta property=\"article:published_time\" content=\"2025-06-27T09:00:56+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2025-06-27T09:00:57+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/ajustica.net\/wp-content\/uploads\/2025\/06\/transferir-3-1.jpeg\" \/>\n\t<meta property=\"og:image:width\" content=\"275\" \/>\n\t<meta property=\"og:image:height\" content=\"183\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"author\" content=\"Portal Justi\u00e7a\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Escrito por\" \/>\n\t<meta name=\"twitter:data1\" content=\"Portal Justi\u00e7a\" \/>\n\t<meta name=\"twitter:label2\" content=\"Est. tempo de leitura\" \/>\n\t<meta name=\"twitter:data2\" content=\"7 minutos\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\/\/schema.org\",\"@graph\":[{\"@type\":\"WebPage\",\"@id\":\"https:\/\/ajustica.net\/index.php\/2025\/06\/27\/banco-sol-pce-osvaldo-macaia-o-protegido-diz-e-faz-conforme-lhe-apetece\/\",\"url\":\"https:\/\/ajustica.net\/index.php\/2025\/06\/27\/banco-sol-pce-osvaldo-macaia-o-protegido-diz-e-faz-conforme-lhe-apetece\/\",\"name\":\"BANCO SOL: PCE OSVALDO MACAIA O PROTEGIDO DIZ E FAZ CONFORME LHE APETECE -\",\"isPartOf\":{\"@id\":\"https:\/\/ajustica.net\/#website\"},\"datePublished\":\"2025-06-27T09:00:56+00:00\",\"dateModified\":\"2025-06-27T09:00:57+00:00\",\"author\":{\"@id\":\"https:\/\/ajustica.net\/#\/schema\/person\/e1f71ed49e0f63898db2951a6b747d62\"},\"breadcrumb\":{\"@id\":\"https:\/\/ajustica.net\/index.php\/2025\/06\/27\/banco-sol-pce-osvaldo-macaia-o-protegido-diz-e-faz-conforme-lhe-apetece\/#breadcrumb\"},\"inLanguage\":\"pt-BR\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\/\/ajustica.net\/index.php\/2025\/06\/27\/banco-sol-pce-osvaldo-macaia-o-protegido-diz-e-faz-conforme-lhe-apetece\/\"]}]},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\/\/ajustica.net\/index.php\/2025\/06\/27\/banco-sol-pce-osvaldo-macaia-o-protegido-diz-e-faz-conforme-lhe-apetece\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"In\u00edcio\",\"item\":\"https:\/\/ajustica.net\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"BANCO SOL: PCE OSVALDO MACAIA O PROTEGIDO DIZ E FAZ CONFORME LHE APETECE\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\/\/ajustica.net\/#website\",\"url\":\"https:\/\/ajustica.net\/\",\"name\":\"\",\"description\":\"Email Para Den\u00fancia: ajusticaa@gmail.com\",\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\/\/ajustica.net\/?s={search_term_string}\"},\"query-input\":\"required name=search_term_string\"}],\"inLanguage\":\"pt-BR\"},{\"@type\":\"Person\",\"@id\":\"https:\/\/ajustica.net\/#\/schema\/person\/e1f71ed49e0f63898db2951a6b747d62\",\"name\":\"Portal Justi\u00e7a\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"pt-BR\",\"@id\":\"https:\/\/ajustica.net\/#\/schema\/person\/image\/\",\"url\":\"https:\/\/secure.gravatar.com\/avatar\/14c19bb3bbce6a73ddabbf74322a5807?s=96&d=mm&r=g\",\"contentUrl\":\"https:\/\/secure.gravatar.com\/avatar\/14c19bb3bbce6a73ddabbf74322a5807?s=96&d=mm&r=g\",\"caption\":\"Portal Justi\u00e7a\"},\"url\":\"https:\/\/ajustica.net\/index.php\/author\/justica\/\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"BANCO SOL: PCE OSVALDO MACAIA O PROTEGIDO DIZ E FAZ CONFORME LHE APETECE -","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/ajustica.net\/index.php\/2025\/06\/27\/banco-sol-pce-osvaldo-macaia-o-protegido-diz-e-faz-conforme-lhe-apetece\/","og_locale":"pt_BR","og_type":"article","og_title":"BANCO SOL: PCE OSVALDO MACAIA O PROTEGIDO DIZ E FAZ CONFORME LHE APETECE -","og_description":"Em Abril de 2024 quando Osvaldo Macaia assumiu o cargo de PCE do Banco Sol supostamente logo a seguir havia feito um diagn\u00f3stico relatando as condi\u00e7\u00f5es em que encontrou a institui\u00e7\u00e3o, sugerindo dentre as ac\u00e7\u00f5es correctivas a diminui\u00e7\u00e3o dos custos e renegocia\u00e7\u00e3o de contratos em vigor na altura, verdade \u00e9 que quase ou nada foi [&hellip;]","og_url":"https:\/\/ajustica.net\/index.php\/2025\/06\/27\/banco-sol-pce-osvaldo-macaia-o-protegido-diz-e-faz-conforme-lhe-apetece\/","article_published_time":"2025-06-27T09:00:56+00:00","article_modified_time":"2025-06-27T09:00:57+00:00","og_image":[{"width":275,"height":183,"url":"https:\/\/ajustica.net\/wp-content\/uploads\/2025\/06\/transferir-3-1.jpeg","type":"image\/jpeg"}],"author":"Portal Justi\u00e7a","twitter_card":"summary_large_image","twitter_misc":{"Escrito por":"Portal Justi\u00e7a","Est. tempo de leitura":"7 minutos"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"WebPage","@id":"https:\/\/ajustica.net\/index.php\/2025\/06\/27\/banco-sol-pce-osvaldo-macaia-o-protegido-diz-e-faz-conforme-lhe-apetece\/","url":"https:\/\/ajustica.net\/index.php\/2025\/06\/27\/banco-sol-pce-osvaldo-macaia-o-protegido-diz-e-faz-conforme-lhe-apetece\/","name":"BANCO SOL: PCE OSVALDO MACAIA O PROTEGIDO DIZ E FAZ CONFORME LHE APETECE -","isPartOf":{"@id":"https:\/\/ajustica.net\/#website"},"datePublished":"2025-06-27T09:00:56+00:00","dateModified":"2025-06-27T09:00:57+00:00","author":{"@id":"https:\/\/ajustica.net\/#\/schema\/person\/e1f71ed49e0f63898db2951a6b747d62"},"breadcrumb":{"@id":"https:\/\/ajustica.net\/index.php\/2025\/06\/27\/banco-sol-pce-osvaldo-macaia-o-protegido-diz-e-faz-conforme-lhe-apetece\/#breadcrumb"},"inLanguage":"pt-BR","potentialAction":[{"@type":"ReadAction","target":["https:\/\/ajustica.net\/index.php\/2025\/06\/27\/banco-sol-pce-osvaldo-macaia-o-protegido-diz-e-faz-conforme-lhe-apetece\/"]}]},{"@type":"BreadcrumbList","@id":"https:\/\/ajustica.net\/index.php\/2025\/06\/27\/banco-sol-pce-osvaldo-macaia-o-protegido-diz-e-faz-conforme-lhe-apetece\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"In\u00edcio","item":"https:\/\/ajustica.net\/"},{"@type":"ListItem","position":2,"name":"BANCO SOL: PCE OSVALDO MACAIA O PROTEGIDO DIZ E FAZ CONFORME LHE APETECE"}]},{"@type":"WebSite","@id":"https:\/\/ajustica.net\/#website","url":"https:\/\/ajustica.net\/","name":"","description":"Email Para Den\u00fancia: ajusticaa@gmail.com","potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/ajustica.net\/?s={search_term_string}"},"query-input":"required name=search_term_string"}],"inLanguage":"pt-BR"},{"@type":"Person","@id":"https:\/\/ajustica.net\/#\/schema\/person\/e1f71ed49e0f63898db2951a6b747d62","name":"Portal Justi\u00e7a","image":{"@type":"ImageObject","inLanguage":"pt-BR","@id":"https:\/\/ajustica.net\/#\/schema\/person\/image\/","url":"https:\/\/secure.gravatar.com\/avatar\/14c19bb3bbce6a73ddabbf74322a5807?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/14c19bb3bbce6a73ddabbf74322a5807?s=96&d=mm&r=g","caption":"Portal Justi\u00e7a"},"url":"https:\/\/ajustica.net\/index.php\/author\/justica\/"}]}},"_links":{"self":[{"href":"https:\/\/ajustica.net\/index.php\/wp-json\/wp\/v2\/posts\/3538"}],"collection":[{"href":"https:\/\/ajustica.net\/index.php\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/ajustica.net\/index.php\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/ajustica.net\/index.php\/wp-json\/wp\/v2\/users\/3"}],"replies":[{"embeddable":true,"href":"https:\/\/ajustica.net\/index.php\/wp-json\/wp\/v2\/comments?post=3538"}],"version-history":[{"count":1,"href":"https:\/\/ajustica.net\/index.php\/wp-json\/wp\/v2\/posts\/3538\/revisions"}],"predecessor-version":[{"id":3540,"href":"https:\/\/ajustica.net\/index.php\/wp-json\/wp\/v2\/posts\/3538\/revisions\/3540"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/ajustica.net\/index.php\/wp-json\/wp\/v2\/media\/3539"}],"wp:attachment":[{"href":"https:\/\/ajustica.net\/index.php\/wp-json\/wp\/v2\/media?parent=3538"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/ajustica.net\/index.php\/wp-json\/wp\/v2\/categories?post=3538"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/ajustica.net\/index.php\/wp-json\/wp\/v2\/tags?post=3538"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}