{"id":3507,"date":"2025-06-22T17:13:58","date_gmt":"2025-06-22T20:13:58","guid":{"rendered":"https:\/\/ajustica.net\/?p=3507"},"modified":"2025-06-22T17:13:58","modified_gmt":"2025-06-22T20:13:58","slug":"eua-aprovam-primeira-vacina-preventiva-contra-o-vih-sida","status":"publish","type":"post","link":"https:\/\/ajustica.net\/index.php\/2025\/06\/22\/eua-aprovam-primeira-vacina-preventiva-contra-o-vih-sida\/","title":{"rendered":"EUA APROVAM PRIMEIRA VACINA PREVENTIVA CONTRA O VIH\/SIDA"},"content":{"rendered":"\n<p>Os Estados Unidos aprovaram, atrav\u00e9s da FDA, o primeiro tratamento preventivo de longa dura\u00e7\u00e3o contra o VIH\/SIDA, denominado Yeztugo (lenacapavir).<\/p>\n\n\n\n<p>Produzido pela farmac\u00eautica Gilead Sciences, o medicamento \u00e9 administrado por injec\u00e7\u00e3o semestral e destina-se a adultos e adolescentes com mais de 35 quilos, oferecendo uma efic\u00e1cia de 99,9% na preven\u00e7\u00e3o da infec\u00e7\u00e3o pelo VIH por via sexual.<\/p>\n\n\n\n<p>Especialistas da \u00e1rea da sa\u00fade consideram o novo tratamento um avan\u00e7o cient\u00edfico marcante e um importante contributo para o combate global ao VIH\/SIDA.<\/p>\n\n\n\n<p>O m\u00e9dico Carlos del Rio destacou o potencial transformador da injec\u00e7\u00e3o na supera\u00e7\u00e3o de obst\u00e1culos como o estigma e a ades\u00e3o \u00e0 medica\u00e7\u00e3o oral di\u00e1ria. J\u00e1 o cirurgi\u00e3o Cruz Vieira e a m\u00e9dica K\u00e1tia Barbas apontaram o Yeztugo como uma promessa concreta no controlo e poss\u00edvel erradica\u00e7\u00e3o da doen\u00e7a.<\/p>\n\n\n\n<p>Com esta aprova\u00e7\u00e3o, cresce a expectativa de que o medicamento contribua para mudar o rumo da luta contra o VIH, especialmente em regi\u00f5es mais afectadas, como a \u00c1frica Subsariana.<\/p>\n\n\n\n<p>A comunidade m\u00e9dica defende agora a necessidade de garantir o acesso equitativo ao tratamento, promovendo a sua distribui\u00e7\u00e3o e a realiza\u00e7\u00e3o de campanhas de sensibiliza\u00e7\u00e3o junto das popula\u00e7\u00f5es vulner\u00e1veis.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Os Estados Unidos aprovaram, atrav\u00e9s da FDA, o primeiro tratamento preventivo de longa dura\u00e7\u00e3o contra o VIH\/SIDA, denominado Yeztugo (lenacapavir). Produzido pela farmac\u00eautica Gilead Sciences, o medicamento \u00e9 administrado por injec\u00e7\u00e3o semestral e destina-se a adultos e adolescentes com mais de 35 quilos, oferecendo uma efic\u00e1cia de 99,9% na preven\u00e7\u00e3o da infec\u00e7\u00e3o pelo VIH por [&hellip;]<\/p>\n","protected":false},"author":3,"featured_media":3508,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[2,6],"tags":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v20.10 - https:\/\/yoast.com\/wordpress\/plugins\/seo\/ -->\n<title>EUA APROVAM PRIMEIRA VACINA PREVENTIVA CONTRA O VIH\/SIDA -<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/ajustica.net\/index.php\/2025\/06\/22\/eua-aprovam-primeira-vacina-preventiva-contra-o-vih-sida\/\" \/>\n<meta property=\"og:locale\" content=\"pt_BR\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"EUA APROVAM PRIMEIRA VACINA PREVENTIVA CONTRA O VIH\/SIDA -\" \/>\n<meta property=\"og:description\" content=\"Os Estados Unidos aprovaram, atrav\u00e9s da FDA, o primeiro tratamento preventivo de longa dura\u00e7\u00e3o contra o VIH\/SIDA, denominado Yeztugo (lenacapavir). Produzido pela farmac\u00eautica Gilead Sciences, o medicamento \u00e9 administrado por injec\u00e7\u00e3o semestral e destina-se a adultos e adolescentes com mais de 35 quilos, oferecendo uma efic\u00e1cia de 99,9% na preven\u00e7\u00e3o da infec\u00e7\u00e3o pelo VIH por [&hellip;]\" \/>\n<meta property=\"og:url\" content=\"https:\/\/ajustica.net\/index.php\/2025\/06\/22\/eua-aprovam-primeira-vacina-preventiva-contra-o-vih-sida\/\" \/>\n<meta property=\"article:published_time\" content=\"2025-06-22T20:13:58+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/ajustica.net\/wp-content\/uploads\/2025\/06\/images.jpeg\" \/>\n\t<meta property=\"og:image:width\" content=\"299\" \/>\n\t<meta property=\"og:image:height\" content=\"168\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"author\" content=\"Portal Justi\u00e7a\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Escrito por\" \/>\n\t<meta name=\"twitter:data1\" content=\"Portal Justi\u00e7a\" \/>\n\t<meta name=\"twitter:label2\" content=\"Est. tempo de leitura\" \/>\n\t<meta name=\"twitter:data2\" content=\"2 minutos\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\/\/schema.org\",\"@graph\":[{\"@type\":\"WebPage\",\"@id\":\"https:\/\/ajustica.net\/index.php\/2025\/06\/22\/eua-aprovam-primeira-vacina-preventiva-contra-o-vih-sida\/\",\"url\":\"https:\/\/ajustica.net\/index.php\/2025\/06\/22\/eua-aprovam-primeira-vacina-preventiva-contra-o-vih-sida\/\",\"name\":\"EUA APROVAM PRIMEIRA VACINA PREVENTIVA CONTRA O VIH\/SIDA -\",\"isPartOf\":{\"@id\":\"https:\/\/ajustica.net\/#website\"},\"datePublished\":\"2025-06-22T20:13:58+00:00\",\"dateModified\":\"2025-06-22T20:13:58+00:00\",\"author\":{\"@id\":\"https:\/\/ajustica.net\/#\/schema\/person\/e1f71ed49e0f63898db2951a6b747d62\"},\"breadcrumb\":{\"@id\":\"https:\/\/ajustica.net\/index.php\/2025\/06\/22\/eua-aprovam-primeira-vacina-preventiva-contra-o-vih-sida\/#breadcrumb\"},\"inLanguage\":\"pt-BR\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\/\/ajustica.net\/index.php\/2025\/06\/22\/eua-aprovam-primeira-vacina-preventiva-contra-o-vih-sida\/\"]}]},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\/\/ajustica.net\/index.php\/2025\/06\/22\/eua-aprovam-primeira-vacina-preventiva-contra-o-vih-sida\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"In\u00edcio\",\"item\":\"https:\/\/ajustica.net\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"EUA APROVAM PRIMEIRA VACINA PREVENTIVA CONTRA O VIH\/SIDA\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\/\/ajustica.net\/#website\",\"url\":\"https:\/\/ajustica.net\/\",\"name\":\"\",\"description\":\"Email Para Den\u00fancia: ajusticaa@gmail.com\",\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\/\/ajustica.net\/?s={search_term_string}\"},\"query-input\":\"required name=search_term_string\"}],\"inLanguage\":\"pt-BR\"},{\"@type\":\"Person\",\"@id\":\"https:\/\/ajustica.net\/#\/schema\/person\/e1f71ed49e0f63898db2951a6b747d62\",\"name\":\"Portal Justi\u00e7a\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"pt-BR\",\"@id\":\"https:\/\/ajustica.net\/#\/schema\/person\/image\/\",\"url\":\"https:\/\/secure.gravatar.com\/avatar\/14c19bb3bbce6a73ddabbf74322a5807?s=96&d=mm&r=g\",\"contentUrl\":\"https:\/\/secure.gravatar.com\/avatar\/14c19bb3bbce6a73ddabbf74322a5807?s=96&d=mm&r=g\",\"caption\":\"Portal Justi\u00e7a\"},\"url\":\"https:\/\/ajustica.net\/index.php\/author\/justica\/\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"EUA APROVAM PRIMEIRA VACINA PREVENTIVA CONTRA O VIH\/SIDA -","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/ajustica.net\/index.php\/2025\/06\/22\/eua-aprovam-primeira-vacina-preventiva-contra-o-vih-sida\/","og_locale":"pt_BR","og_type":"article","og_title":"EUA APROVAM PRIMEIRA VACINA PREVENTIVA CONTRA O VIH\/SIDA -","og_description":"Os Estados Unidos aprovaram, atrav\u00e9s da FDA, o primeiro tratamento preventivo de longa dura\u00e7\u00e3o contra o VIH\/SIDA, denominado Yeztugo (lenacapavir). Produzido pela farmac\u00eautica Gilead Sciences, o medicamento \u00e9 administrado por injec\u00e7\u00e3o semestral e destina-se a adultos e adolescentes com mais de 35 quilos, oferecendo uma efic\u00e1cia de 99,9% na preven\u00e7\u00e3o da infec\u00e7\u00e3o pelo VIH por [&hellip;]","og_url":"https:\/\/ajustica.net\/index.php\/2025\/06\/22\/eua-aprovam-primeira-vacina-preventiva-contra-o-vih-sida\/","article_published_time":"2025-06-22T20:13:58+00:00","og_image":[{"width":299,"height":168,"url":"https:\/\/ajustica.net\/wp-content\/uploads\/2025\/06\/images.jpeg","type":"image\/jpeg"}],"author":"Portal Justi\u00e7a","twitter_card":"summary_large_image","twitter_misc":{"Escrito por":"Portal Justi\u00e7a","Est. tempo de leitura":"2 minutos"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"WebPage","@id":"https:\/\/ajustica.net\/index.php\/2025\/06\/22\/eua-aprovam-primeira-vacina-preventiva-contra-o-vih-sida\/","url":"https:\/\/ajustica.net\/index.php\/2025\/06\/22\/eua-aprovam-primeira-vacina-preventiva-contra-o-vih-sida\/","name":"EUA APROVAM PRIMEIRA VACINA PREVENTIVA CONTRA O VIH\/SIDA -","isPartOf":{"@id":"https:\/\/ajustica.net\/#website"},"datePublished":"2025-06-22T20:13:58+00:00","dateModified":"2025-06-22T20:13:58+00:00","author":{"@id":"https:\/\/ajustica.net\/#\/schema\/person\/e1f71ed49e0f63898db2951a6b747d62"},"breadcrumb":{"@id":"https:\/\/ajustica.net\/index.php\/2025\/06\/22\/eua-aprovam-primeira-vacina-preventiva-contra-o-vih-sida\/#breadcrumb"},"inLanguage":"pt-BR","potentialAction":[{"@type":"ReadAction","target":["https:\/\/ajustica.net\/index.php\/2025\/06\/22\/eua-aprovam-primeira-vacina-preventiva-contra-o-vih-sida\/"]}]},{"@type":"BreadcrumbList","@id":"https:\/\/ajustica.net\/index.php\/2025\/06\/22\/eua-aprovam-primeira-vacina-preventiva-contra-o-vih-sida\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"In\u00edcio","item":"https:\/\/ajustica.net\/"},{"@type":"ListItem","position":2,"name":"EUA APROVAM PRIMEIRA VACINA PREVENTIVA CONTRA O VIH\/SIDA"}]},{"@type":"WebSite","@id":"https:\/\/ajustica.net\/#website","url":"https:\/\/ajustica.net\/","name":"","description":"Email Para Den\u00fancia: ajusticaa@gmail.com","potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/ajustica.net\/?s={search_term_string}"},"query-input":"required name=search_term_string"}],"inLanguage":"pt-BR"},{"@type":"Person","@id":"https:\/\/ajustica.net\/#\/schema\/person\/e1f71ed49e0f63898db2951a6b747d62","name":"Portal Justi\u00e7a","image":{"@type":"ImageObject","inLanguage":"pt-BR","@id":"https:\/\/ajustica.net\/#\/schema\/person\/image\/","url":"https:\/\/secure.gravatar.com\/avatar\/14c19bb3bbce6a73ddabbf74322a5807?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/14c19bb3bbce6a73ddabbf74322a5807?s=96&d=mm&r=g","caption":"Portal Justi\u00e7a"},"url":"https:\/\/ajustica.net\/index.php\/author\/justica\/"}]}},"_links":{"self":[{"href":"https:\/\/ajustica.net\/index.php\/wp-json\/wp\/v2\/posts\/3507"}],"collection":[{"href":"https:\/\/ajustica.net\/index.php\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/ajustica.net\/index.php\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/ajustica.net\/index.php\/wp-json\/wp\/v2\/users\/3"}],"replies":[{"embeddable":true,"href":"https:\/\/ajustica.net\/index.php\/wp-json\/wp\/v2\/comments?post=3507"}],"version-history":[{"count":1,"href":"https:\/\/ajustica.net\/index.php\/wp-json\/wp\/v2\/posts\/3507\/revisions"}],"predecessor-version":[{"id":3509,"href":"https:\/\/ajustica.net\/index.php\/wp-json\/wp\/v2\/posts\/3507\/revisions\/3509"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/ajustica.net\/index.php\/wp-json\/wp\/v2\/media\/3508"}],"wp:attachment":[{"href":"https:\/\/ajustica.net\/index.php\/wp-json\/wp\/v2\/media?parent=3507"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/ajustica.net\/index.php\/wp-json\/wp\/v2\/categories?post=3507"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/ajustica.net\/index.php\/wp-json\/wp\/v2\/tags?post=3507"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}