{"id":3212,"date":"2025-03-30T15:55:24","date_gmt":"2025-03-30T18:55:24","guid":{"rendered":"https:\/\/ajustica.net\/?p=3212"},"modified":"2025-03-30T15:55:26","modified_gmt":"2025-03-30T18:55:26","slug":"coruupcao-epinosul-desqualificada-de-concurso-publico-e-contratada-pelo-porto-de-luanda","status":"publish","type":"post","link":"https:\/\/ajustica.net\/index.php\/2025\/03\/30\/coruupcao-epinosul-desqualificada-de-concurso-publico-e-contratada-pelo-porto-de-luanda\/","title":{"rendered":"CORUUP\u00c7\u00c3O: EPINOSUL, DESQUALIFICADA DE CONCURSO P\u00daBLICO, \u00c9 CONTRATADA PELO PORTO DE LUANDA"},"content":{"rendered":"\n<p>Os trabalhadores da empresa EPINOSUL, que se dedica \u00e0 atraca\u00e7\u00e3o e desatraca\u00e7\u00e3o de navios no Porto de Luanda (PL) acusam a direc\u00e7\u00e3o da empresa de persegui\u00e7\u00e3o dos funcion\u00e1rios, que reclamam viola\u00e7\u00e3o dos seus direitos.<\/p>\n\n\n\n<p>POR: A JUSTI\u00c7A<\/p>\n\n\n\n<p>A EPINOSUL, segundo apurou O Decreto, foi desqualificada e afastada de um concurso p\u00fablico de reboque e amarra\u00e7\u00e3o no Porto de Luanda, realizada recentemente, por motivos t\u00e9cnicos e financeiros, mas fontes que acompanham o processo revelam que os respons\u00e1veis da empresa EPINOSUL e o Porto, celebraram um novo contrato para continuarem a gerirem o sector mar\u00edtimo do porto de Luanda, uma vez que o contrato passado expirou no dia 18 de Dezembro de 2024.<\/p>\n\n\n\n<p>A fonte ressalta que foram feitos esquemas de corrup\u00e7\u00e3o e tr\u00e1fico de influ\u00eancia, que culminaram com a assinatura de um novo contrato entre as duas institui\u00e7\u00f5es, sem um concurso p\u00fablico.<\/p>\n\n\n\n<p>\u201cEstamos diante de uma corrup\u00e7\u00e3o activa no sector mar\u00edtimo do porto de Luanda, o que compromete o combate \u00e0 corrup\u00e7\u00e3o que \u00e9 a bandeira do Presidente da Rep\u00fablica e do MPLA, Jo\u00e3o Louren\u00e7o\u201d.<\/p>\n\n\n\n<p>Os trabalhadores apelam aos \u00f3rg\u00e3os de direito que intervenham no caso e investiguem, para que se apure \u201co que realmente se passa no sector mar\u00edtimo do Porto de Luanda, ouvindo igualmente n\u00f3s os trabalhadores da empresa EPINOSUL, nos ajudem, por favor\u201d, clamam em anonimato.<\/p>\n\n\n\n<p>Ressaltam que, apesar dos v\u00e1rios apelos lan\u00e7ados \u00e0s autoridades competentes ao longo do ano de 2024, os problemas na EPINOSUL continuam. \u201cO pensamento da actual direc\u00e7\u00e3o da empresa encabe\u00e7ada pelos senhores Jos\u00e9 Lu\u00eds de Oliveira e George Bartolomeu Jo\u00e3o, \u00e9 tornar os trabalhadores mendigos do que j\u00e1 s\u00e3o, pois as condi\u00e7\u00f5es sociais dos trabalhadores s\u00e3o prec\u00e1rias e lastim\u00e1veis para uma empresa que \u00e9 produtora\u201d.<\/p>\n\n\n\n<p>&nbsp;\u201c\u00c9 tanta maldade com os profissionais, que at\u00e9 um empr\u00e9stimo monet\u00e1rio na ordem dos 20 mil kwanzas, que seriam descontados ao trabalhador no seu sal\u00e1rio, n\u00e3o \u00e9 f\u00e1cil a sua aprova\u00e7\u00e3o, a n\u00e3o ser que seja amigo do administrador delegado George Bartolomeu Jo\u00e3o, ou em outros casos ser um informante\u201d, contou um dos trabalhadores.<\/p>\n\n\n\n<p>As persegui\u00e7\u00f5es, segundo ainda os denunciantes, v\u00e3o desde descontos injustificados e despedimentos sem justa causa, bem como a n\u00e3o presta\u00e7\u00e3o de apoios aos trabalhadores doentes, ou apoio aos familiares, em caso de morte do trabalhador.<\/p>\n\n\n\n<p>\u201cRecentemente faleceu um trabalhador com cerca de 30 anos de servi\u00e7o, e ajuda que a empresa EPINOSUL deu \u00e0 fam\u00edlia foi de 100 mil kwanzas, uma pr\u00e1tica que tem sido recorrente pela direc\u00e7\u00e3o liderada por Jos\u00e9 Lu\u00eds de Oliveira com o seu coadjuvante George Bartolomeu Jo\u00e3o\u201d, lamentou outro trabalhador.<\/p>\n\n\n\n<p>\u201cNas empresas em que a EPINOSUL presta servi\u00e7os reconhecem o trabalho dos seus t\u00e9cnicos, algumas delas oferecem est\u00edmulos, mas a direc\u00e7\u00e3o da EPINOSUL sente-se por isso. Ser\u00e1 que os s\u00f3cios da referida empresa e o&nbsp; Porto de Luanda se agradam com isto?\u201d, questionam.<\/p>\n\n\n\n<p>\u201cPor favor, esta mensagem vai aqu\u00e9m de direito neste pa\u00eds para que fa\u00e7a alguma coisa por esses trabalhadores, que tudo fazem para que o Porto de Luanda (sector mar\u00edtimo) continue a servir o pa\u00eds e n\u00e3o s\u00f3\u201d, apelam.<\/p>\n\n\n\n<p>Este portal tentou, sem sucesso, ouvir a direc\u00e7\u00e3o da EPINOSUL.<\/p>\n\n\n\n<p>O Decreto<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Os trabalhadores da empresa EPINOSUL, que se dedica \u00e0 atraca\u00e7\u00e3o e desatraca\u00e7\u00e3o de navios no Porto de Luanda (PL) acusam a direc\u00e7\u00e3o da empresa de persegui\u00e7\u00e3o dos funcion\u00e1rios, que reclamam viola\u00e7\u00e3o dos seus direitos. POR: A JUSTI\u00c7A A EPINOSUL, segundo apurou O Decreto, foi desqualificada e afastada de um concurso p\u00fablico de reboque e amarra\u00e7\u00e3o [&hellip;]<\/p>\n","protected":false},"author":3,"featured_media":3213,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[3,2],"tags":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v20.10 - https:\/\/yoast.com\/wordpress\/plugins\/seo\/ -->\n<title>CORUUP\u00c7\u00c3O: EPINOSUL, DESQUALIFICADA DE CONCURSO P\u00daBLICO, \u00c9 CONTRATADA PELO PORTO DE LUANDA -<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/ajustica.net\/index.php\/2025\/03\/30\/coruupcao-epinosul-desqualificada-de-concurso-publico-e-contratada-pelo-porto-de-luanda\/\" \/>\n<meta property=\"og:locale\" content=\"pt_BR\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"CORUUP\u00c7\u00c3O: EPINOSUL, DESQUALIFICADA DE CONCURSO P\u00daBLICO, \u00c9 CONTRATADA PELO PORTO DE LUANDA -\" \/>\n<meta property=\"og:description\" content=\"Os trabalhadores da empresa EPINOSUL, que se dedica \u00e0 atraca\u00e7\u00e3o e desatraca\u00e7\u00e3o de navios no Porto de Luanda (PL) acusam a direc\u00e7\u00e3o da empresa de persegui\u00e7\u00e3o dos funcion\u00e1rios, que reclamam viola\u00e7\u00e3o dos seus direitos. POR: A JUSTI\u00c7A A EPINOSUL, segundo apurou O Decreto, foi desqualificada e afastada de um concurso p\u00fablico de reboque e amarra\u00e7\u00e3o [&hellip;]\" \/>\n<meta property=\"og:url\" content=\"https:\/\/ajustica.net\/index.php\/2025\/03\/30\/coruupcao-epinosul-desqualificada-de-concurso-publico-e-contratada-pelo-porto-de-luanda\/\" \/>\n<meta property=\"article:published_time\" content=\"2025-03-30T18:55:24+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2025-03-30T18:55:26+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/ajustica.net\/wp-content\/uploads\/2025\/03\/EPINOSUL.jpeg\" \/>\n\t<meta property=\"og:image:width\" content=\"654\" \/>\n\t<meta property=\"og:image:height\" content=\"411\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"author\" content=\"Portal Justi\u00e7a\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Escrito por\" \/>\n\t<meta name=\"twitter:data1\" content=\"Portal Justi\u00e7a\" \/>\n\t<meta name=\"twitter:label2\" content=\"Est. tempo de leitura\" \/>\n\t<meta name=\"twitter:data2\" content=\"3 minutos\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\/\/schema.org\",\"@graph\":[{\"@type\":\"WebPage\",\"@id\":\"https:\/\/ajustica.net\/index.php\/2025\/03\/30\/coruupcao-epinosul-desqualificada-de-concurso-publico-e-contratada-pelo-porto-de-luanda\/\",\"url\":\"https:\/\/ajustica.net\/index.php\/2025\/03\/30\/coruupcao-epinosul-desqualificada-de-concurso-publico-e-contratada-pelo-porto-de-luanda\/\",\"name\":\"CORUUP\u00c7\u00c3O: EPINOSUL, DESQUALIFICADA DE CONCURSO P\u00daBLICO, \u00c9 CONTRATADA PELO PORTO DE LUANDA -\",\"isPartOf\":{\"@id\":\"https:\/\/ajustica.net\/#website\"},\"datePublished\":\"2025-03-30T18:55:24+00:00\",\"dateModified\":\"2025-03-30T18:55:26+00:00\",\"author\":{\"@id\":\"https:\/\/ajustica.net\/#\/schema\/person\/e1f71ed49e0f63898db2951a6b747d62\"},\"breadcrumb\":{\"@id\":\"https:\/\/ajustica.net\/index.php\/2025\/03\/30\/coruupcao-epinosul-desqualificada-de-concurso-publico-e-contratada-pelo-porto-de-luanda\/#breadcrumb\"},\"inLanguage\":\"pt-BR\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\/\/ajustica.net\/index.php\/2025\/03\/30\/coruupcao-epinosul-desqualificada-de-concurso-publico-e-contratada-pelo-porto-de-luanda\/\"]}]},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\/\/ajustica.net\/index.php\/2025\/03\/30\/coruupcao-epinosul-desqualificada-de-concurso-publico-e-contratada-pelo-porto-de-luanda\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"In\u00edcio\",\"item\":\"https:\/\/ajustica.net\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"CORUUP\u00c7\u00c3O: EPINOSUL, DESQUALIFICADA DE CONCURSO P\u00daBLICO, \u00c9 CONTRATADA PELO PORTO DE LUANDA\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\/\/ajustica.net\/#website\",\"url\":\"https:\/\/ajustica.net\/\",\"name\":\"\",\"description\":\"Email Para Den\u00fancia: ajusticaa@gmail.com\",\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\/\/ajustica.net\/?s={search_term_string}\"},\"query-input\":\"required name=search_term_string\"}],\"inLanguage\":\"pt-BR\"},{\"@type\":\"Person\",\"@id\":\"https:\/\/ajustica.net\/#\/schema\/person\/e1f71ed49e0f63898db2951a6b747d62\",\"name\":\"Portal Justi\u00e7a\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"pt-BR\",\"@id\":\"https:\/\/ajustica.net\/#\/schema\/person\/image\/\",\"url\":\"https:\/\/secure.gravatar.com\/avatar\/14c19bb3bbce6a73ddabbf74322a5807?s=96&d=mm&r=g\",\"contentUrl\":\"https:\/\/secure.gravatar.com\/avatar\/14c19bb3bbce6a73ddabbf74322a5807?s=96&d=mm&r=g\",\"caption\":\"Portal Justi\u00e7a\"},\"url\":\"https:\/\/ajustica.net\/index.php\/author\/justica\/\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"CORUUP\u00c7\u00c3O: EPINOSUL, DESQUALIFICADA DE CONCURSO P\u00daBLICO, \u00c9 CONTRATADA PELO PORTO DE LUANDA -","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/ajustica.net\/index.php\/2025\/03\/30\/coruupcao-epinosul-desqualificada-de-concurso-publico-e-contratada-pelo-porto-de-luanda\/","og_locale":"pt_BR","og_type":"article","og_title":"CORUUP\u00c7\u00c3O: EPINOSUL, DESQUALIFICADA DE CONCURSO P\u00daBLICO, \u00c9 CONTRATADA PELO PORTO DE LUANDA -","og_description":"Os trabalhadores da empresa EPINOSUL, que se dedica \u00e0 atraca\u00e7\u00e3o e desatraca\u00e7\u00e3o de navios no Porto de Luanda (PL) acusam a direc\u00e7\u00e3o da empresa de persegui\u00e7\u00e3o dos funcion\u00e1rios, que reclamam viola\u00e7\u00e3o dos seus direitos. POR: A JUSTI\u00c7A A EPINOSUL, segundo apurou O Decreto, foi desqualificada e afastada de um concurso p\u00fablico de reboque e amarra\u00e7\u00e3o [&hellip;]","og_url":"https:\/\/ajustica.net\/index.php\/2025\/03\/30\/coruupcao-epinosul-desqualificada-de-concurso-publico-e-contratada-pelo-porto-de-luanda\/","article_published_time":"2025-03-30T18:55:24+00:00","article_modified_time":"2025-03-30T18:55:26+00:00","og_image":[{"width":654,"height":411,"url":"https:\/\/ajustica.net\/wp-content\/uploads\/2025\/03\/EPINOSUL.jpeg","type":"image\/jpeg"}],"author":"Portal Justi\u00e7a","twitter_card":"summary_large_image","twitter_misc":{"Escrito por":"Portal Justi\u00e7a","Est. tempo de leitura":"3 minutos"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"WebPage","@id":"https:\/\/ajustica.net\/index.php\/2025\/03\/30\/coruupcao-epinosul-desqualificada-de-concurso-publico-e-contratada-pelo-porto-de-luanda\/","url":"https:\/\/ajustica.net\/index.php\/2025\/03\/30\/coruupcao-epinosul-desqualificada-de-concurso-publico-e-contratada-pelo-porto-de-luanda\/","name":"CORUUP\u00c7\u00c3O: EPINOSUL, DESQUALIFICADA DE CONCURSO P\u00daBLICO, \u00c9 CONTRATADA PELO PORTO DE LUANDA -","isPartOf":{"@id":"https:\/\/ajustica.net\/#website"},"datePublished":"2025-03-30T18:55:24+00:00","dateModified":"2025-03-30T18:55:26+00:00","author":{"@id":"https:\/\/ajustica.net\/#\/schema\/person\/e1f71ed49e0f63898db2951a6b747d62"},"breadcrumb":{"@id":"https:\/\/ajustica.net\/index.php\/2025\/03\/30\/coruupcao-epinosul-desqualificada-de-concurso-publico-e-contratada-pelo-porto-de-luanda\/#breadcrumb"},"inLanguage":"pt-BR","potentialAction":[{"@type":"ReadAction","target":["https:\/\/ajustica.net\/index.php\/2025\/03\/30\/coruupcao-epinosul-desqualificada-de-concurso-publico-e-contratada-pelo-porto-de-luanda\/"]}]},{"@type":"BreadcrumbList","@id":"https:\/\/ajustica.net\/index.php\/2025\/03\/30\/coruupcao-epinosul-desqualificada-de-concurso-publico-e-contratada-pelo-porto-de-luanda\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"In\u00edcio","item":"https:\/\/ajustica.net\/"},{"@type":"ListItem","position":2,"name":"CORUUP\u00c7\u00c3O: EPINOSUL, DESQUALIFICADA DE CONCURSO P\u00daBLICO, \u00c9 CONTRATADA PELO PORTO DE LUANDA"}]},{"@type":"WebSite","@id":"https:\/\/ajustica.net\/#website","url":"https:\/\/ajustica.net\/","name":"","description":"Email Para Den\u00fancia: ajusticaa@gmail.com","potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/ajustica.net\/?s={search_term_string}"},"query-input":"required name=search_term_string"}],"inLanguage":"pt-BR"},{"@type":"Person","@id":"https:\/\/ajustica.net\/#\/schema\/person\/e1f71ed49e0f63898db2951a6b747d62","name":"Portal Justi\u00e7a","image":{"@type":"ImageObject","inLanguage":"pt-BR","@id":"https:\/\/ajustica.net\/#\/schema\/person\/image\/","url":"https:\/\/secure.gravatar.com\/avatar\/14c19bb3bbce6a73ddabbf74322a5807?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/14c19bb3bbce6a73ddabbf74322a5807?s=96&d=mm&r=g","caption":"Portal Justi\u00e7a"},"url":"https:\/\/ajustica.net\/index.php\/author\/justica\/"}]}},"_links":{"self":[{"href":"https:\/\/ajustica.net\/index.php\/wp-json\/wp\/v2\/posts\/3212"}],"collection":[{"href":"https:\/\/ajustica.net\/index.php\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/ajustica.net\/index.php\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/ajustica.net\/index.php\/wp-json\/wp\/v2\/users\/3"}],"replies":[{"embeddable":true,"href":"https:\/\/ajustica.net\/index.php\/wp-json\/wp\/v2\/comments?post=3212"}],"version-history":[{"count":1,"href":"https:\/\/ajustica.net\/index.php\/wp-json\/wp\/v2\/posts\/3212\/revisions"}],"predecessor-version":[{"id":3214,"href":"https:\/\/ajustica.net\/index.php\/wp-json\/wp\/v2\/posts\/3212\/revisions\/3214"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/ajustica.net\/index.php\/wp-json\/wp\/v2\/media\/3213"}],"wp:attachment":[{"href":"https:\/\/ajustica.net\/index.php\/wp-json\/wp\/v2\/media?parent=3212"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/ajustica.net\/index.php\/wp-json\/wp\/v2\/categories?post=3212"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/ajustica.net\/index.php\/wp-json\/wp\/v2\/tags?post=3212"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}