{"id":3190,"date":"2025-03-26T07:34:10","date_gmt":"2025-03-26T10:34:10","guid":{"rendered":"https:\/\/ajustica.net\/?p=3190"},"modified":"2025-03-26T07:34:10","modified_gmt":"2025-03-26T10:34:10","slug":"a-verdade-dos-factos-sonangol-esclarece-falcatruas-da-akwaba-contra-angoflex-que-iliba-empresa-chinesa-zhong-hentai","status":"publish","type":"post","link":"https:\/\/ajustica.net\/index.php\/2025\/03\/26\/a-verdade-dos-factos-sonangol-esclarece-falcatruas-da-akwaba-contra-angoflex-que-iliba-empresa-chinesa-zhong-hentai\/","title":{"rendered":"A VERDADE DOS FACTOS: SONANGOL ESCLARECE FALCATRUAS DA AKWABA CONTRA ANGOFLEX QUE ILIBA EMPRESA CHINESA ZHONG HENTAI"},"content":{"rendered":"\n<p>A Sociedade Nacional de Combust\u00edveis de Angola, E.P. (Sonangol), desmente a falcratuas da empresa Akwaba Group, Com\u00e9rcio e Ind\u00fastria acusada de tomar de assalto a unidade fabril da empresa Zhongan Hengtai, em refer\u00eancia ao of\u00edcio n\u00ba 32\/TCL\/UAJG\/2025, datado de 17 de Janeiro de 2025,&nbsp; no qual informam sobre o andamento do processo criminal que envolve a empresa acusada (Akwaba) e notificam o PCA da Sonangol para auxiliar o Tribunal nas dilig\u00eancias.<\/p>\n\n\n\n<p>Num documentos em posse do Jornal Hora H, enviado pela Sonangol ao Tribunal Dona Ana Joaquina, a Sonangol esclarece que celebrou, em 30 de Julho de 2014, um Contrato de Constitui\u00e7\u00e3o de Direito de Superf\u00edcie com o Governo Provincial do Bengo, que lhe concedeu o direito de superf\u00edcie sobre uma parcela de terreno de 500.500 m\u00b2, localizada na Barra do Dande, na prov\u00edncia do Bengo.<\/p>\n\n\n\n<p>Adicionalmente, explica o documento, por mandato governamental de 26 de Agosto de 2004, foi atribu\u00edda \u00e0 Sonangol a responsabilidade pela constru\u00e7\u00e3o e opera\u00e7\u00e3o de uma ponte cais para desembarque e embarque de enrolamento de tubos, al\u00e9m da constru\u00e7\u00e3o de um estaleiro para montagem de condutas de tubos (Base de Enrolamento).<\/p>\n\n\n\n<p>Em 28 de Dezembro de 2004, a Sonangol, juntamente com a sua empresa participada Angoflex Industrial, Lda. assinou um Contrato de Cess\u00e3o de Direitos de Uso para a constru\u00e7\u00e3o e opera\u00e7\u00e3o da referida infraestrutura, a ser implantada na parcela de terreno mencionada, que passou a ser chamada de Base.<\/p>\n\n\n\n<p>No entanto, diz o documento datado de 14 de Fevereiro de 2025, a Akwaba n\u00e3o cumpriu com o pagamento do valor acordado no prazo estipulado no contrato, ou seja, dentro de 15 dias ap\u00f3s a sua assinatura, o que resultou na rescis\u00e3o do contrato.<\/p>\n\n\n\n<p>\u201cPosteriormente, a Angoflex, por meio de concurso p\u00fablico, adjudicou os referidos bens m\u00f3veis \u00e0 empresa Zhongan Hengtai &#8211; Ind\u00fastria, Lda., tendo sido celebrados os respectivos contratos, efectuados os pagamentos e concretizada a entrega dos bens\u201d, l\u00ea-se.<\/p>\n\n\n\n<p>Entretanto, no dia 29 de Janeiro de 2025, a Sonangol foi informada, por meio da empresa de seguran\u00e7a V\u00e3o V\u00e3o, de que um oficial de dilig\u00eancias, acompanhado por efectivos do Servi\u00e7o de Investiga\u00e7\u00e3o Criminal, agentes da Pol\u00edcia Nacional e representantes da Akwaba, compareceu \u00e0 Base com uma notifica\u00e7\u00e3o, supostamente para dar conhecimento de um despacho exarado pelo Merit\u00edssimo Juiz de Garantias. No entanto, n\u00e3o foi entregue qualquer c\u00f3pia do despacho, e foi ordenada a retirada dos agentes de seguran\u00e7a da V\u00e3o V\u00e3o, a apreens\u00e3o das suas armas e a substitui\u00e7\u00e3o por outros dois seguran\u00e7as indicados pelo referido oficial de dilig\u00eancias.<\/p>\n\n\n\n<p>\u201cCumpre destacar que a Sonangol, E.P. \u00e9 uma empresa p\u00fablica e que, consequentemente, os seus activos imobili\u00e1rios e mobili\u00e1rios constituem patrim\u00f3nio do Estado, nos termos da Lei n.\u00ba 18\/10, de 6 de Agosto (Lei do Patrim\u00f3nio P\u00fablico), pelo que n\u00e3o existe qualquer interesse privado sobre a Base, e os bens m\u00f3veis l\u00e1 existente, conforme quer demonstrar-se na reclama\u00e7\u00e3o\u201d, terminou o documento.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>A Sociedade Nacional de Combust\u00edveis de Angola, E.P. (Sonangol), desmente a falcratuas da empresa Akwaba Group, Com\u00e9rcio e Ind\u00fastria acusada de tomar de assalto a unidade fabril da empresa Zhongan Hengtai, em refer\u00eancia ao of\u00edcio n\u00ba 32\/TCL\/UAJG\/2025, datado de 17 de Janeiro de 2025,&nbsp; no qual informam sobre o andamento do processo criminal que envolve [&hellip;]<\/p>\n","protected":false},"author":3,"featured_media":3191,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[3,2],"tags":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v20.10 - https:\/\/yoast.com\/wordpress\/plugins\/seo\/ -->\n<title>A VERDADE DOS FACTOS: SONANGOL ESCLARECE FALCATRUAS DA AKWABA CONTRA ANGOFLEX QUE ILIBA EMPRESA CHINESA ZHONG HENTAI -<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/ajustica.net\/index.php\/2025\/03\/26\/a-verdade-dos-factos-sonangol-esclarece-falcatruas-da-akwaba-contra-angoflex-que-iliba-empresa-chinesa-zhong-hentai\/\" \/>\n<meta property=\"og:locale\" content=\"pt_BR\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"A VERDADE DOS FACTOS: SONANGOL ESCLARECE FALCATRUAS DA AKWABA CONTRA ANGOFLEX QUE ILIBA EMPRESA CHINESA ZHONG HENTAI -\" \/>\n<meta property=\"og:description\" content=\"A Sociedade Nacional de Combust\u00edveis de Angola, E.P. (Sonangol), desmente a falcratuas da empresa Akwaba Group, Com\u00e9rcio e Ind\u00fastria acusada de tomar de assalto a unidade fabril da empresa Zhongan Hengtai, em refer\u00eancia ao of\u00edcio n\u00ba 32\/TCL\/UAJG\/2025, datado de 17 de Janeiro de 2025,&nbsp; no qual informam sobre o andamento do processo criminal que envolve [&hellip;]\" \/>\n<meta property=\"og:url\" content=\"https:\/\/ajustica.net\/index.php\/2025\/03\/26\/a-verdade-dos-factos-sonangol-esclarece-falcatruas-da-akwaba-contra-angoflex-que-iliba-empresa-chinesa-zhong-hentai\/\" \/>\n<meta property=\"article:published_time\" content=\"2025-03-26T10:34:10+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/ajustica.net\/wp-content\/uploads\/2025\/03\/4fa6491b-1b3c-4c96-88a9-c5cc1dd899b1.jpeg\" \/>\n\t<meta property=\"og:image:width\" content=\"828\" \/>\n\t<meta property=\"og:image:height\" content=\"576\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"author\" content=\"Portal Justi\u00e7a\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Escrito por\" \/>\n\t<meta name=\"twitter:data1\" content=\"Portal Justi\u00e7a\" \/>\n\t<meta name=\"twitter:label2\" content=\"Est. tempo de leitura\" \/>\n\t<meta name=\"twitter:data2\" content=\"3 minutos\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\/\/schema.org\",\"@graph\":[{\"@type\":\"WebPage\",\"@id\":\"https:\/\/ajustica.net\/index.php\/2025\/03\/26\/a-verdade-dos-factos-sonangol-esclarece-falcatruas-da-akwaba-contra-angoflex-que-iliba-empresa-chinesa-zhong-hentai\/\",\"url\":\"https:\/\/ajustica.net\/index.php\/2025\/03\/26\/a-verdade-dos-factos-sonangol-esclarece-falcatruas-da-akwaba-contra-angoflex-que-iliba-empresa-chinesa-zhong-hentai\/\",\"name\":\"A VERDADE DOS FACTOS: SONANGOL ESCLARECE FALCATRUAS DA AKWABA CONTRA ANGOFLEX QUE ILIBA EMPRESA CHINESA ZHONG HENTAI -\",\"isPartOf\":{\"@id\":\"https:\/\/ajustica.net\/#website\"},\"datePublished\":\"2025-03-26T10:34:10+00:00\",\"dateModified\":\"2025-03-26T10:34:10+00:00\",\"author\":{\"@id\":\"https:\/\/ajustica.net\/#\/schema\/person\/e1f71ed49e0f63898db2951a6b747d62\"},\"breadcrumb\":{\"@id\":\"https:\/\/ajustica.net\/index.php\/2025\/03\/26\/a-verdade-dos-factos-sonangol-esclarece-falcatruas-da-akwaba-contra-angoflex-que-iliba-empresa-chinesa-zhong-hentai\/#breadcrumb\"},\"inLanguage\":\"pt-BR\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\/\/ajustica.net\/index.php\/2025\/03\/26\/a-verdade-dos-factos-sonangol-esclarece-falcatruas-da-akwaba-contra-angoflex-que-iliba-empresa-chinesa-zhong-hentai\/\"]}]},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\/\/ajustica.net\/index.php\/2025\/03\/26\/a-verdade-dos-factos-sonangol-esclarece-falcatruas-da-akwaba-contra-angoflex-que-iliba-empresa-chinesa-zhong-hentai\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"In\u00edcio\",\"item\":\"https:\/\/ajustica.net\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"A VERDADE DOS FACTOS: SONANGOL ESCLARECE FALCATRUAS DA AKWABA CONTRA ANGOFLEX QUE ILIBA EMPRESA CHINESA ZHONG HENTAI\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\/\/ajustica.net\/#website\",\"url\":\"https:\/\/ajustica.net\/\",\"name\":\"\",\"description\":\"Email Para Den\u00fancia: ajusticaa@gmail.com\",\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\/\/ajustica.net\/?s={search_term_string}\"},\"query-input\":\"required name=search_term_string\"}],\"inLanguage\":\"pt-BR\"},{\"@type\":\"Person\",\"@id\":\"https:\/\/ajustica.net\/#\/schema\/person\/e1f71ed49e0f63898db2951a6b747d62\",\"name\":\"Portal Justi\u00e7a\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"pt-BR\",\"@id\":\"https:\/\/ajustica.net\/#\/schema\/person\/image\/\",\"url\":\"https:\/\/secure.gravatar.com\/avatar\/14c19bb3bbce6a73ddabbf74322a5807?s=96&d=mm&r=g\",\"contentUrl\":\"https:\/\/secure.gravatar.com\/avatar\/14c19bb3bbce6a73ddabbf74322a5807?s=96&d=mm&r=g\",\"caption\":\"Portal Justi\u00e7a\"},\"url\":\"https:\/\/ajustica.net\/index.php\/author\/justica\/\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"A VERDADE DOS FACTOS: SONANGOL ESCLARECE FALCATRUAS DA AKWABA CONTRA ANGOFLEX QUE ILIBA EMPRESA CHINESA ZHONG HENTAI -","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/ajustica.net\/index.php\/2025\/03\/26\/a-verdade-dos-factos-sonangol-esclarece-falcatruas-da-akwaba-contra-angoflex-que-iliba-empresa-chinesa-zhong-hentai\/","og_locale":"pt_BR","og_type":"article","og_title":"A VERDADE DOS FACTOS: SONANGOL ESCLARECE FALCATRUAS DA AKWABA CONTRA ANGOFLEX QUE ILIBA EMPRESA CHINESA ZHONG HENTAI -","og_description":"A Sociedade Nacional de Combust\u00edveis de Angola, E.P. (Sonangol), desmente a falcratuas da empresa Akwaba Group, Com\u00e9rcio e Ind\u00fastria acusada de tomar de assalto a unidade fabril da empresa Zhongan Hengtai, em refer\u00eancia ao of\u00edcio n\u00ba 32\/TCL\/UAJG\/2025, datado de 17 de Janeiro de 2025,&nbsp; no qual informam sobre o andamento do processo criminal que envolve [&hellip;]","og_url":"https:\/\/ajustica.net\/index.php\/2025\/03\/26\/a-verdade-dos-factos-sonangol-esclarece-falcatruas-da-akwaba-contra-angoflex-que-iliba-empresa-chinesa-zhong-hentai\/","article_published_time":"2025-03-26T10:34:10+00:00","og_image":[{"width":828,"height":576,"url":"https:\/\/ajustica.net\/wp-content\/uploads\/2025\/03\/4fa6491b-1b3c-4c96-88a9-c5cc1dd899b1.jpeg","type":"image\/jpeg"}],"author":"Portal Justi\u00e7a","twitter_card":"summary_large_image","twitter_misc":{"Escrito por":"Portal Justi\u00e7a","Est. tempo de leitura":"3 minutos"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"WebPage","@id":"https:\/\/ajustica.net\/index.php\/2025\/03\/26\/a-verdade-dos-factos-sonangol-esclarece-falcatruas-da-akwaba-contra-angoflex-que-iliba-empresa-chinesa-zhong-hentai\/","url":"https:\/\/ajustica.net\/index.php\/2025\/03\/26\/a-verdade-dos-factos-sonangol-esclarece-falcatruas-da-akwaba-contra-angoflex-que-iliba-empresa-chinesa-zhong-hentai\/","name":"A VERDADE DOS FACTOS: SONANGOL ESCLARECE FALCATRUAS DA AKWABA CONTRA ANGOFLEX QUE ILIBA EMPRESA CHINESA ZHONG HENTAI -","isPartOf":{"@id":"https:\/\/ajustica.net\/#website"},"datePublished":"2025-03-26T10:34:10+00:00","dateModified":"2025-03-26T10:34:10+00:00","author":{"@id":"https:\/\/ajustica.net\/#\/schema\/person\/e1f71ed49e0f63898db2951a6b747d62"},"breadcrumb":{"@id":"https:\/\/ajustica.net\/index.php\/2025\/03\/26\/a-verdade-dos-factos-sonangol-esclarece-falcatruas-da-akwaba-contra-angoflex-que-iliba-empresa-chinesa-zhong-hentai\/#breadcrumb"},"inLanguage":"pt-BR","potentialAction":[{"@type":"ReadAction","target":["https:\/\/ajustica.net\/index.php\/2025\/03\/26\/a-verdade-dos-factos-sonangol-esclarece-falcatruas-da-akwaba-contra-angoflex-que-iliba-empresa-chinesa-zhong-hentai\/"]}]},{"@type":"BreadcrumbList","@id":"https:\/\/ajustica.net\/index.php\/2025\/03\/26\/a-verdade-dos-factos-sonangol-esclarece-falcatruas-da-akwaba-contra-angoflex-que-iliba-empresa-chinesa-zhong-hentai\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"In\u00edcio","item":"https:\/\/ajustica.net\/"},{"@type":"ListItem","position":2,"name":"A VERDADE DOS FACTOS: SONANGOL ESCLARECE FALCATRUAS DA AKWABA CONTRA ANGOFLEX QUE ILIBA EMPRESA CHINESA ZHONG HENTAI"}]},{"@type":"WebSite","@id":"https:\/\/ajustica.net\/#website","url":"https:\/\/ajustica.net\/","name":"","description":"Email Para Den\u00fancia: ajusticaa@gmail.com","potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/ajustica.net\/?s={search_term_string}"},"query-input":"required name=search_term_string"}],"inLanguage":"pt-BR"},{"@type":"Person","@id":"https:\/\/ajustica.net\/#\/schema\/person\/e1f71ed49e0f63898db2951a6b747d62","name":"Portal Justi\u00e7a","image":{"@type":"ImageObject","inLanguage":"pt-BR","@id":"https:\/\/ajustica.net\/#\/schema\/person\/image\/","url":"https:\/\/secure.gravatar.com\/avatar\/14c19bb3bbce6a73ddabbf74322a5807?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/14c19bb3bbce6a73ddabbf74322a5807?s=96&d=mm&r=g","caption":"Portal Justi\u00e7a"},"url":"https:\/\/ajustica.net\/index.php\/author\/justica\/"}]}},"_links":{"self":[{"href":"https:\/\/ajustica.net\/index.php\/wp-json\/wp\/v2\/posts\/3190"}],"collection":[{"href":"https:\/\/ajustica.net\/index.php\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/ajustica.net\/index.php\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/ajustica.net\/index.php\/wp-json\/wp\/v2\/users\/3"}],"replies":[{"embeddable":true,"href":"https:\/\/ajustica.net\/index.php\/wp-json\/wp\/v2\/comments?post=3190"}],"version-history":[{"count":1,"href":"https:\/\/ajustica.net\/index.php\/wp-json\/wp\/v2\/posts\/3190\/revisions"}],"predecessor-version":[{"id":3192,"href":"https:\/\/ajustica.net\/index.php\/wp-json\/wp\/v2\/posts\/3190\/revisions\/3192"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/ajustica.net\/index.php\/wp-json\/wp\/v2\/media\/3191"}],"wp:attachment":[{"href":"https:\/\/ajustica.net\/index.php\/wp-json\/wp\/v2\/media?parent=3190"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/ajustica.net\/index.php\/wp-json\/wp\/v2\/categories?post=3190"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/ajustica.net\/index.php\/wp-json\/wp\/v2\/tags?post=3190"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}