{"id":2749,"date":"2024-12-05T20:08:21","date_gmt":"2024-12-05T23:08:21","guid":{"rendered":"https:\/\/ajustica.net\/?p=2749"},"modified":"2024-12-05T20:08:22","modified_gmt":"2024-12-05T23:08:22","slug":"bi-campeao-olimpico-sofre-acidente-grave","status":"publish","type":"post","link":"https:\/\/ajustica.net\/index.php\/2024\/12\/05\/bi-campeao-olimpico-sofre-acidente-grave\/","title":{"rendered":"BI-CAMPE\u00c3O OL\u00cdMPICO SOFRE ACIDENTE GRAVE"},"content":{"rendered":"\n<p>A Soudal-Quick Step actualizou,ontem, o estado de sa\u00fade do ciclista Remco Evenepoel, ap\u00f3s este ter sido atropelado durante um treino. De acordo com comunicado da equipa, o belga &#8220;sofreu fracturas na costela, na omoplata direita e na m\u00e3o direita&#8221;.<\/p>\n\n\n\n<p>A equipa informa ainda que o duplo campe\u00e3o ol\u00edmpico em Paris&#8217;2024 foi inicialmente &#8220;levado para o Hospital Erasmus, em Anderlecht&#8221;, sendo que agora transitar\u00e1 para outra unidade hospitalar, em Herentals, onde, &#8220;juntamente com a equipa m\u00e9dica da Soudal Quick-Step, a sua situa\u00e7\u00e3o cl\u00ednica ser\u00e1 avaliada&#8221; no sentido de se tra\u00e7ar um plano de recupera\u00e7\u00e3o tendo em vista a temporada de 2025.<\/p>\n\n\n\n<p>O regresso come\u00e7a agora para Remco Evenepoel, garantiu ontem o ciclista belga, 24 anos, admitindo que enfrentar\u00e1 uma &#8220;longa jornada&#8221; de recupera\u00e7\u00e3o ap\u00f3s o acidente de treino que sofreu na ter\u00e7a-feira.<\/p>\n\n\n\n<p>&#8220;O regresso come\u00e7a agora&#8221;, titulou Evenepoel numa publica\u00e7\u00e3o nas redes sociais, onde surge com o bra\u00e7o ao peito, depois de ter sido operado \u00e0 clav\u00edcula direita na noite passada, numa interven\u00e7\u00e3o que &#8220;correu bem&#8221;.<\/p>\n\n\n\n<p>O &#8220;acidente assustador&#8221; que sofreu &#8211; embateu contra a porta de um ve\u00edculo dos correios, depois de a carteira a ter aberto abruptamente &#8211; deixou-o com fracturas numa costela, omoplata e m\u00e3o direitas, contus\u00f5es nos pulm\u00f5es e &#8220;uma desloca\u00e7\u00e3o da clav\u00edcula direita, que rasgou os ligamentos envolventes&#8221;.<\/p>\n\n\n\n<p>&#8220;Vai ser uma longa jornada, mas estou plenamente focado na minha recupera\u00e7\u00e3o e determinado a regressar mais forte, passo a passo&#8221;, escreveu o duplo campe\u00e3o ol\u00edmpico em Paris&#8217;2024.<\/p>\n\n\n\n<p>O corredor da Soudal Quick-Step agradeceu o apoio que recebeu nas \u00faltimas 24 horas, nomeadamente dos servi\u00e7os m\u00e9dicos, mas tamb\u00e9m dos &#8220;vizinhos&#8221; que o ajudaram no momento da colis\u00e3o com a carrinha dos correios, deixando tamb\u00e9m uma palavra de apoio \u00e0 carteira envolvida no acidente.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>A Soudal-Quick Step actualizou,ontem, o estado de sa\u00fade do ciclista Remco Evenepoel, ap\u00f3s este ter sido atropelado durante um treino. De acordo com comunicado da equipa, o belga &#8220;sofreu fracturas na costela, na omoplata direita e na m\u00e3o direita&#8221;. A equipa informa ainda que o duplo campe\u00e3o ol\u00edmpico em Paris&#8217;2024 foi inicialmente &#8220;levado para o [&hellip;]<\/p>\n","protected":false},"author":3,"featured_media":2750,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[6],"tags":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v20.10 - https:\/\/yoast.com\/wordpress\/plugins\/seo\/ -->\n<title>BI-CAMPE\u00c3O OL\u00cdMPICO SOFRE ACIDENTE GRAVE -<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/ajustica.net\/index.php\/2024\/12\/05\/bi-campeao-olimpico-sofre-acidente-grave\/\" \/>\n<meta property=\"og:locale\" content=\"pt_BR\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"BI-CAMPE\u00c3O OL\u00cdMPICO SOFRE ACIDENTE GRAVE -\" \/>\n<meta property=\"og:description\" content=\"A Soudal-Quick Step actualizou,ontem, o estado de sa\u00fade do ciclista Remco Evenepoel, ap\u00f3s este ter sido atropelado durante um treino. De acordo com comunicado da equipa, o belga &#8220;sofreu fracturas na costela, na omoplata direita e na m\u00e3o direita&#8221;. A equipa informa ainda que o duplo campe\u00e3o ol\u00edmpico em Paris&#8217;2024 foi inicialmente &#8220;levado para o [&hellip;]\" \/>\n<meta property=\"og:url\" content=\"https:\/\/ajustica.net\/index.php\/2024\/12\/05\/bi-campeao-olimpico-sofre-acidente-grave\/\" \/>\n<meta property=\"article:published_time\" content=\"2024-12-05T23:08:21+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2024-12-05T23:08:22+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/ajustica.net\/wp-content\/uploads\/2024\/12\/6234560_imagem.jpeg\" \/>\n\t<meta property=\"og:image:width\" content=\"462\" \/>\n\t<meta property=\"og:image:height\" content=\"355\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"author\" content=\"Portal Justi\u00e7a\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Escrito por\" \/>\n\t<meta name=\"twitter:data1\" content=\"Portal Justi\u00e7a\" \/>\n\t<meta name=\"twitter:label2\" content=\"Est. tempo de leitura\" \/>\n\t<meta name=\"twitter:data2\" content=\"2 minutos\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\/\/schema.org\",\"@graph\":[{\"@type\":\"WebPage\",\"@id\":\"https:\/\/ajustica.net\/index.php\/2024\/12\/05\/bi-campeao-olimpico-sofre-acidente-grave\/\",\"url\":\"https:\/\/ajustica.net\/index.php\/2024\/12\/05\/bi-campeao-olimpico-sofre-acidente-grave\/\",\"name\":\"BI-CAMPE\u00c3O OL\u00cdMPICO SOFRE ACIDENTE GRAVE -\",\"isPartOf\":{\"@id\":\"https:\/\/ajustica.net\/#website\"},\"datePublished\":\"2024-12-05T23:08:21+00:00\",\"dateModified\":\"2024-12-05T23:08:22+00:00\",\"author\":{\"@id\":\"https:\/\/ajustica.net\/#\/schema\/person\/e1f71ed49e0f63898db2951a6b747d62\"},\"breadcrumb\":{\"@id\":\"https:\/\/ajustica.net\/index.php\/2024\/12\/05\/bi-campeao-olimpico-sofre-acidente-grave\/#breadcrumb\"},\"inLanguage\":\"pt-BR\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\/\/ajustica.net\/index.php\/2024\/12\/05\/bi-campeao-olimpico-sofre-acidente-grave\/\"]}]},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\/\/ajustica.net\/index.php\/2024\/12\/05\/bi-campeao-olimpico-sofre-acidente-grave\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"In\u00edcio\",\"item\":\"https:\/\/ajustica.net\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"BI-CAMPE\u00c3O OL\u00cdMPICO SOFRE ACIDENTE GRAVE\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\/\/ajustica.net\/#website\",\"url\":\"https:\/\/ajustica.net\/\",\"name\":\"\",\"description\":\"Email Para Den\u00fancia: ajusticaa@gmail.com\",\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\/\/ajustica.net\/?s={search_term_string}\"},\"query-input\":\"required name=search_term_string\"}],\"inLanguage\":\"pt-BR\"},{\"@type\":\"Person\",\"@id\":\"https:\/\/ajustica.net\/#\/schema\/person\/e1f71ed49e0f63898db2951a6b747d62\",\"name\":\"Portal Justi\u00e7a\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"pt-BR\",\"@id\":\"https:\/\/ajustica.net\/#\/schema\/person\/image\/\",\"url\":\"https:\/\/secure.gravatar.com\/avatar\/14c19bb3bbce6a73ddabbf74322a5807?s=96&d=mm&r=g\",\"contentUrl\":\"https:\/\/secure.gravatar.com\/avatar\/14c19bb3bbce6a73ddabbf74322a5807?s=96&d=mm&r=g\",\"caption\":\"Portal Justi\u00e7a\"},\"url\":\"https:\/\/ajustica.net\/index.php\/author\/justica\/\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"BI-CAMPE\u00c3O OL\u00cdMPICO SOFRE ACIDENTE GRAVE -","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/ajustica.net\/index.php\/2024\/12\/05\/bi-campeao-olimpico-sofre-acidente-grave\/","og_locale":"pt_BR","og_type":"article","og_title":"BI-CAMPE\u00c3O OL\u00cdMPICO SOFRE ACIDENTE GRAVE -","og_description":"A Soudal-Quick Step actualizou,ontem, o estado de sa\u00fade do ciclista Remco Evenepoel, ap\u00f3s este ter sido atropelado durante um treino. De acordo com comunicado da equipa, o belga &#8220;sofreu fracturas na costela, na omoplata direita e na m\u00e3o direita&#8221;. A equipa informa ainda que o duplo campe\u00e3o ol\u00edmpico em Paris&#8217;2024 foi inicialmente &#8220;levado para o [&hellip;]","og_url":"https:\/\/ajustica.net\/index.php\/2024\/12\/05\/bi-campeao-olimpico-sofre-acidente-grave\/","article_published_time":"2024-12-05T23:08:21+00:00","article_modified_time":"2024-12-05T23:08:22+00:00","og_image":[{"width":462,"height":355,"url":"https:\/\/ajustica.net\/wp-content\/uploads\/2024\/12\/6234560_imagem.jpeg","type":"image\/jpeg"}],"author":"Portal Justi\u00e7a","twitter_card":"summary_large_image","twitter_misc":{"Escrito por":"Portal Justi\u00e7a","Est. tempo de leitura":"2 minutos"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"WebPage","@id":"https:\/\/ajustica.net\/index.php\/2024\/12\/05\/bi-campeao-olimpico-sofre-acidente-grave\/","url":"https:\/\/ajustica.net\/index.php\/2024\/12\/05\/bi-campeao-olimpico-sofre-acidente-grave\/","name":"BI-CAMPE\u00c3O OL\u00cdMPICO SOFRE ACIDENTE GRAVE -","isPartOf":{"@id":"https:\/\/ajustica.net\/#website"},"datePublished":"2024-12-05T23:08:21+00:00","dateModified":"2024-12-05T23:08:22+00:00","author":{"@id":"https:\/\/ajustica.net\/#\/schema\/person\/e1f71ed49e0f63898db2951a6b747d62"},"breadcrumb":{"@id":"https:\/\/ajustica.net\/index.php\/2024\/12\/05\/bi-campeao-olimpico-sofre-acidente-grave\/#breadcrumb"},"inLanguage":"pt-BR","potentialAction":[{"@type":"ReadAction","target":["https:\/\/ajustica.net\/index.php\/2024\/12\/05\/bi-campeao-olimpico-sofre-acidente-grave\/"]}]},{"@type":"BreadcrumbList","@id":"https:\/\/ajustica.net\/index.php\/2024\/12\/05\/bi-campeao-olimpico-sofre-acidente-grave\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"In\u00edcio","item":"https:\/\/ajustica.net\/"},{"@type":"ListItem","position":2,"name":"BI-CAMPE\u00c3O OL\u00cdMPICO SOFRE ACIDENTE GRAVE"}]},{"@type":"WebSite","@id":"https:\/\/ajustica.net\/#website","url":"https:\/\/ajustica.net\/","name":"","description":"Email Para Den\u00fancia: ajusticaa@gmail.com","potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/ajustica.net\/?s={search_term_string}"},"query-input":"required name=search_term_string"}],"inLanguage":"pt-BR"},{"@type":"Person","@id":"https:\/\/ajustica.net\/#\/schema\/person\/e1f71ed49e0f63898db2951a6b747d62","name":"Portal Justi\u00e7a","image":{"@type":"ImageObject","inLanguage":"pt-BR","@id":"https:\/\/ajustica.net\/#\/schema\/person\/image\/","url":"https:\/\/secure.gravatar.com\/avatar\/14c19bb3bbce6a73ddabbf74322a5807?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/14c19bb3bbce6a73ddabbf74322a5807?s=96&d=mm&r=g","caption":"Portal Justi\u00e7a"},"url":"https:\/\/ajustica.net\/index.php\/author\/justica\/"}]}},"_links":{"self":[{"href":"https:\/\/ajustica.net\/index.php\/wp-json\/wp\/v2\/posts\/2749"}],"collection":[{"href":"https:\/\/ajustica.net\/index.php\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/ajustica.net\/index.php\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/ajustica.net\/index.php\/wp-json\/wp\/v2\/users\/3"}],"replies":[{"embeddable":true,"href":"https:\/\/ajustica.net\/index.php\/wp-json\/wp\/v2\/comments?post=2749"}],"version-history":[{"count":1,"href":"https:\/\/ajustica.net\/index.php\/wp-json\/wp\/v2\/posts\/2749\/revisions"}],"predecessor-version":[{"id":2751,"href":"https:\/\/ajustica.net\/index.php\/wp-json\/wp\/v2\/posts\/2749\/revisions\/2751"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/ajustica.net\/index.php\/wp-json\/wp\/v2\/media\/2750"}],"wp:attachment":[{"href":"https:\/\/ajustica.net\/index.php\/wp-json\/wp\/v2\/media?parent=2749"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/ajustica.net\/index.php\/wp-json\/wp\/v2\/categories?post=2749"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/ajustica.net\/index.php\/wp-json\/wp\/v2\/tags?post=2749"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}