{"id":2736,"date":"2024-12-02T17:59:43","date_gmt":"2024-12-02T20:59:43","guid":{"rendered":"https:\/\/ajustica.net\/?p=2736"},"modified":"2024-12-02T17:59:44","modified_gmt":"2024-12-02T20:59:44","slug":"xe-meninos-nao-falem-do-que-nao-existe-direitos-humanos","status":"publish","type":"post","link":"https:\/\/ajustica.net\/index.php\/2024\/12\/02\/xe-meninos-nao-falem-do-que-nao-existe-direitos-humanos\/","title":{"rendered":"X\u00c9 MENINOS, N\u00c3O FALEM DO QUE N\u00c3O EXISTE (DIREITOS HUMANOS)"},"content":{"rendered":"\n<p>Organiza\u00e7\u00f5es N\u00e3o-Governamentais (ONG) pediram hoje a interven\u00e7\u00e3o do Presidente angolano, general Jo\u00e3o Louren\u00e7o, para a liberta\u00e7\u00e3o de activistas que classificam de \u201cpresos pol\u00edticos\u201d e disseram que o sistema judicial est\u00e1 \u201cgravemente enfermo\u201d e mant\u00e9m \u201crela\u00e7\u00e3o incestuosa\u201d com o poder executivo cujo titular \u00e9 um \u201cvelho\u201d amigo dos dois presidentes que s\u00e3o donos de Angola, o do MPLA e o da re(i)p\u00fablica.<\/p>\n\n\n\n<p>AFriends of Angola (FoA) e o Observat\u00f3rio para Coes\u00e3o Social e Justi\u00e7a (OCSJ), organiza\u00e7\u00f5es n\u00e3o-governamentais angolanas manifestaram indigna\u00e7\u00e3o em torno da \u201cpris\u00e3o injusta\u201d dos activistas Gilson da Silva Moreira \u201cTanaice Neutro\u201d, Hermenegildo Andr\u00e9 \u201cGildo das Ruas\u201d, Abra\u00e3o dos Santos \u201cPensador\u201d e Adolfo Campos, presos desde Setembro de 2023.<\/p>\n\n\n\n<p>Segundo as ONG, que em confer\u00eancia de imprensa instaram o Presidente\/General a libertar os referidos activistas, estes s\u00e3o parte de uma \u201clonga lista de cidad\u00e3os que representam injustamente o quadro de presos pol\u00edticos ou prisioneiros de consci\u00eancia\u201d em Angola.<\/p>\n\n\n\n<p>\u201cEsta realidade entende-se contr\u00e1ria aos valores de um Estado democr\u00e1tico e de direito, pois, em democracia n\u00e3o deve haver presos pol\u00edticos\u201d, defenderam. Ainda n\u00e3o perceberam que Angola n\u00e3o \u00e9 aquilo que gostariam que fosse, uma democracia e um Estado de Direito.<\/p>\n\n\n\n<p>Desde a \u201cinjusta deten\u00e7\u00e3o\u201d dos activistas (em Setembro de 2023 quando protestavam em solidariedade \u00e0 manifesta\u00e7\u00e3o de motoxatistas em Luanda), consideram as ONG, tudo quanto devia ser feito em sua defesa foi realizado, mas \u201clamentavelmente n\u00e3o se conseguiu ter uma explica\u00e7\u00e3o nacional da sua deten\u00e7\u00e3o\u201d.<\/p>\n\n\n\n<p>Para estas organiza\u00e7\u00f5es c\u00edvicas, a priva\u00e7\u00e3o das liberdades dos activistas n\u00e3o obedeceu aos c\u00e2nones da lei e nem dos procedimentos judiciais, \u201ctendo sido um acto pol\u00edtico de ataque \u00e0s liberdades que ironicamente foi realizado dentro do tribunal somente para demonstrar que o regime quando quer pode\u201d.<\/p>\n\n\n\n<p>Estes foram condenados pelos crimes de desobedi\u00eancia e resist\u00eancia, condena\u00e7\u00f5es que, para o advogado e presidente do OCSJ, Zola Bambi, foram \u201cinjustas e tiveram motiva\u00e7\u00f5es pol\u00edticas\u201d.<\/p>\n\n\n\n<p>\u201cOs activistas estiveram sujeitos a linchamento judicial, simplesmente para intimidar, esvaziar o espa\u00e7o c\u00edvico e criar um clima de medo no seio dos cidad\u00e3os em Angola\u201d, criticou, referindo que a liberdade dos mesmos \u201cdepende das ordens superiores que provavelmente emanar\u00e3o do titular do poder executivo e n\u00e3o dos procedimentos legais\u201d.<\/p>\n\n\n\n<p>Florindo Chivucute, presidente da FoA, lamentou o que denominou de nega\u00e7\u00e3o de justi\u00e7a e a morosidade processual neste caso que envolve os quatro activistas, desde o acesso, pagamento das guias, documentos para o seguimento processual, pedindo mesmo interven\u00e7\u00e3o do Presidente angolano.<\/p>\n\n\n\n<p>\u201cSenhor Presidente, coloque esses jovens em liberdade, porque eu n\u00e3o sei qual \u00e9 o objectivo, estamos cansados dessas brincadeiras e o executivo angolano tem que ser mais s\u00e9rio e n\u00e3o estar a violar a Constitui\u00e7\u00e3o constantemente para cultivar o medo entre os angolanos\u201d, salientou.<\/p>\n\n\n\n<p>No entender da FoA e do OCJS, o sistema judicial angolano \u201cest\u00e1 gravemente enfermo, n\u00e3o funciona com independ\u00eancia, alguns tribunais est\u00e3o transformados em extens\u00e3o dos comit\u00e9s de especialidade do partido no poder (MPLA)\u201d.<\/p>\n\n\n\n<p>Deste modo, \u201cest\u00e1 tamb\u00e9m partidarizada a realiza\u00e7\u00e3o da justi\u00e7a de acordo com os interesses dos que actualmente governam o pa\u00eds. Pior \u00e9 a instrumentaliza\u00e7\u00e3o da Justi\u00e7a e a rela\u00e7\u00e3o incestuosa da influ\u00eancia e controlo destas institui\u00e7\u00f5es pelo titular do poder executivo\u201d, acrescentam.<\/p>\n\n\n\n<p>\u201cEsta nefasta alquimia, demonstra claramente as sev\u00edcias que os activistas foram submetidos, lhes foi aplicado o direito penal do inimigo\u201d, enfatizam ainda as ONG, pedindo \u201cliberta\u00e7\u00e3o imediata e reposi\u00e7\u00e3o da justi\u00e7a digna\u201d para os activistas.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Organiza\u00e7\u00f5es N\u00e3o-Governamentais (ONG) pediram hoje a interven\u00e7\u00e3o do Presidente angolano, general Jo\u00e3o Louren\u00e7o, para a liberta\u00e7\u00e3o de activistas que classificam de \u201cpresos pol\u00edticos\u201d e disseram que o sistema judicial est\u00e1 \u201cgravemente enfermo\u201d e mant\u00e9m \u201crela\u00e7\u00e3o incestuosa\u201d com o poder executivo cujo titular \u00e9 um \u201cvelho\u201d amigo dos dois presidentes que s\u00e3o donos de Angola, o [&hellip;]<\/p>\n","protected":false},"author":3,"featured_media":2737,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[2,5],"tags":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v20.10 - https:\/\/yoast.com\/wordpress\/plugins\/seo\/ -->\n<title>X\u00c9 MENINOS, N\u00c3O FALEM DO QUE N\u00c3O EXISTE (DIREITOS HUMANOS) -<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/ajustica.net\/index.php\/2024\/12\/02\/xe-meninos-nao-falem-do-que-nao-existe-direitos-humanos\/\" \/>\n<meta property=\"og:locale\" content=\"pt_BR\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"X\u00c9 MENINOS, N\u00c3O FALEM DO QUE N\u00c3O EXISTE (DIREITOS HUMANOS) -\" \/>\n<meta property=\"og:description\" content=\"Organiza\u00e7\u00f5es N\u00e3o-Governamentais (ONG) pediram hoje a interven\u00e7\u00e3o do Presidente angolano, general Jo\u00e3o Louren\u00e7o, para a liberta\u00e7\u00e3o de activistas que classificam de \u201cpresos pol\u00edticos\u201d e disseram que o sistema judicial est\u00e1 \u201cgravemente enfermo\u201d e mant\u00e9m \u201crela\u00e7\u00e3o incestuosa\u201d com o poder executivo cujo titular \u00e9 um \u201cvelho\u201d amigo dos dois presidentes que s\u00e3o donos de Angola, o [&hellip;]\" \/>\n<meta property=\"og:url\" content=\"https:\/\/ajustica.net\/index.php\/2024\/12\/02\/xe-meninos-nao-falem-do-que-nao-existe-direitos-humanos\/\" \/>\n<meta property=\"article:published_time\" content=\"2024-12-02T20:59:43+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2024-12-02T20:59:44+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/ajustica.net\/wp-content\/uploads\/2024\/12\/floyd.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"840\" \/>\n\t<meta property=\"og:image:height\" content=\"480\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"author\" content=\"Portal Justi\u00e7a\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Escrito por\" \/>\n\t<meta name=\"twitter:data1\" content=\"Portal Justi\u00e7a\" \/>\n\t<meta name=\"twitter:label2\" content=\"Est. tempo de leitura\" \/>\n\t<meta name=\"twitter:data2\" content=\"4 minutos\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\/\/schema.org\",\"@graph\":[{\"@type\":\"WebPage\",\"@id\":\"https:\/\/ajustica.net\/index.php\/2024\/12\/02\/xe-meninos-nao-falem-do-que-nao-existe-direitos-humanos\/\",\"url\":\"https:\/\/ajustica.net\/index.php\/2024\/12\/02\/xe-meninos-nao-falem-do-que-nao-existe-direitos-humanos\/\",\"name\":\"X\u00c9 MENINOS, N\u00c3O FALEM DO QUE N\u00c3O EXISTE (DIREITOS HUMANOS) -\",\"isPartOf\":{\"@id\":\"https:\/\/ajustica.net\/#website\"},\"datePublished\":\"2024-12-02T20:59:43+00:00\",\"dateModified\":\"2024-12-02T20:59:44+00:00\",\"author\":{\"@id\":\"https:\/\/ajustica.net\/#\/schema\/person\/e1f71ed49e0f63898db2951a6b747d62\"},\"breadcrumb\":{\"@id\":\"https:\/\/ajustica.net\/index.php\/2024\/12\/02\/xe-meninos-nao-falem-do-que-nao-existe-direitos-humanos\/#breadcrumb\"},\"inLanguage\":\"pt-BR\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\/\/ajustica.net\/index.php\/2024\/12\/02\/xe-meninos-nao-falem-do-que-nao-existe-direitos-humanos\/\"]}]},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\/\/ajustica.net\/index.php\/2024\/12\/02\/xe-meninos-nao-falem-do-que-nao-existe-direitos-humanos\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"In\u00edcio\",\"item\":\"https:\/\/ajustica.net\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"X\u00c9 MENINOS, N\u00c3O FALEM DO QUE N\u00c3O EXISTE (DIREITOS HUMANOS)\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\/\/ajustica.net\/#website\",\"url\":\"https:\/\/ajustica.net\/\",\"name\":\"\",\"description\":\"Email Para Den\u00fancia: ajusticaa@gmail.com\",\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\/\/ajustica.net\/?s={search_term_string}\"},\"query-input\":\"required name=search_term_string\"}],\"inLanguage\":\"pt-BR\"},{\"@type\":\"Person\",\"@id\":\"https:\/\/ajustica.net\/#\/schema\/person\/e1f71ed49e0f63898db2951a6b747d62\",\"name\":\"Portal Justi\u00e7a\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"pt-BR\",\"@id\":\"https:\/\/ajustica.net\/#\/schema\/person\/image\/\",\"url\":\"https:\/\/secure.gravatar.com\/avatar\/14c19bb3bbce6a73ddabbf74322a5807?s=96&d=mm&r=g\",\"contentUrl\":\"https:\/\/secure.gravatar.com\/avatar\/14c19bb3bbce6a73ddabbf74322a5807?s=96&d=mm&r=g\",\"caption\":\"Portal Justi\u00e7a\"},\"url\":\"https:\/\/ajustica.net\/index.php\/author\/justica\/\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"X\u00c9 MENINOS, N\u00c3O FALEM DO QUE N\u00c3O EXISTE (DIREITOS HUMANOS) -","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/ajustica.net\/index.php\/2024\/12\/02\/xe-meninos-nao-falem-do-que-nao-existe-direitos-humanos\/","og_locale":"pt_BR","og_type":"article","og_title":"X\u00c9 MENINOS, N\u00c3O FALEM DO QUE N\u00c3O EXISTE (DIREITOS HUMANOS) -","og_description":"Organiza\u00e7\u00f5es N\u00e3o-Governamentais (ONG) pediram hoje a interven\u00e7\u00e3o do Presidente angolano, general Jo\u00e3o Louren\u00e7o, para a liberta\u00e7\u00e3o de activistas que classificam de \u201cpresos pol\u00edticos\u201d e disseram que o sistema judicial est\u00e1 \u201cgravemente enfermo\u201d e mant\u00e9m \u201crela\u00e7\u00e3o incestuosa\u201d com o poder executivo cujo titular \u00e9 um \u201cvelho\u201d amigo dos dois presidentes que s\u00e3o donos de Angola, o [&hellip;]","og_url":"https:\/\/ajustica.net\/index.php\/2024\/12\/02\/xe-meninos-nao-falem-do-que-nao-existe-direitos-humanos\/","article_published_time":"2024-12-02T20:59:43+00:00","article_modified_time":"2024-12-02T20:59:44+00:00","og_image":[{"width":840,"height":480,"url":"https:\/\/ajustica.net\/wp-content\/uploads\/2024\/12\/floyd.jpg","type":"image\/jpeg"}],"author":"Portal Justi\u00e7a","twitter_card":"summary_large_image","twitter_misc":{"Escrito por":"Portal Justi\u00e7a","Est. tempo de leitura":"4 minutos"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"WebPage","@id":"https:\/\/ajustica.net\/index.php\/2024\/12\/02\/xe-meninos-nao-falem-do-que-nao-existe-direitos-humanos\/","url":"https:\/\/ajustica.net\/index.php\/2024\/12\/02\/xe-meninos-nao-falem-do-que-nao-existe-direitos-humanos\/","name":"X\u00c9 MENINOS, N\u00c3O FALEM DO QUE N\u00c3O EXISTE (DIREITOS HUMANOS) -","isPartOf":{"@id":"https:\/\/ajustica.net\/#website"},"datePublished":"2024-12-02T20:59:43+00:00","dateModified":"2024-12-02T20:59:44+00:00","author":{"@id":"https:\/\/ajustica.net\/#\/schema\/person\/e1f71ed49e0f63898db2951a6b747d62"},"breadcrumb":{"@id":"https:\/\/ajustica.net\/index.php\/2024\/12\/02\/xe-meninos-nao-falem-do-que-nao-existe-direitos-humanos\/#breadcrumb"},"inLanguage":"pt-BR","potentialAction":[{"@type":"ReadAction","target":["https:\/\/ajustica.net\/index.php\/2024\/12\/02\/xe-meninos-nao-falem-do-que-nao-existe-direitos-humanos\/"]}]},{"@type":"BreadcrumbList","@id":"https:\/\/ajustica.net\/index.php\/2024\/12\/02\/xe-meninos-nao-falem-do-que-nao-existe-direitos-humanos\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"In\u00edcio","item":"https:\/\/ajustica.net\/"},{"@type":"ListItem","position":2,"name":"X\u00c9 MENINOS, N\u00c3O FALEM DO QUE N\u00c3O EXISTE (DIREITOS HUMANOS)"}]},{"@type":"WebSite","@id":"https:\/\/ajustica.net\/#website","url":"https:\/\/ajustica.net\/","name":"","description":"Email Para Den\u00fancia: ajusticaa@gmail.com","potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/ajustica.net\/?s={search_term_string}"},"query-input":"required name=search_term_string"}],"inLanguage":"pt-BR"},{"@type":"Person","@id":"https:\/\/ajustica.net\/#\/schema\/person\/e1f71ed49e0f63898db2951a6b747d62","name":"Portal Justi\u00e7a","image":{"@type":"ImageObject","inLanguage":"pt-BR","@id":"https:\/\/ajustica.net\/#\/schema\/person\/image\/","url":"https:\/\/secure.gravatar.com\/avatar\/14c19bb3bbce6a73ddabbf74322a5807?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/14c19bb3bbce6a73ddabbf74322a5807?s=96&d=mm&r=g","caption":"Portal Justi\u00e7a"},"url":"https:\/\/ajustica.net\/index.php\/author\/justica\/"}]}},"_links":{"self":[{"href":"https:\/\/ajustica.net\/index.php\/wp-json\/wp\/v2\/posts\/2736"}],"collection":[{"href":"https:\/\/ajustica.net\/index.php\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/ajustica.net\/index.php\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/ajustica.net\/index.php\/wp-json\/wp\/v2\/users\/3"}],"replies":[{"embeddable":true,"href":"https:\/\/ajustica.net\/index.php\/wp-json\/wp\/v2\/comments?post=2736"}],"version-history":[{"count":1,"href":"https:\/\/ajustica.net\/index.php\/wp-json\/wp\/v2\/posts\/2736\/revisions"}],"predecessor-version":[{"id":2738,"href":"https:\/\/ajustica.net\/index.php\/wp-json\/wp\/v2\/posts\/2736\/revisions\/2738"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/ajustica.net\/index.php\/wp-json\/wp\/v2\/media\/2737"}],"wp:attachment":[{"href":"https:\/\/ajustica.net\/index.php\/wp-json\/wp\/v2\/media?parent=2736"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/ajustica.net\/index.php\/wp-json\/wp\/v2\/categories?post=2736"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/ajustica.net\/index.php\/wp-json\/wp\/v2\/tags?post=2736"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}