{"id":2683,"date":"2024-11-14T17:44:17","date_gmt":"2024-11-14T20:44:17","guid":{"rendered":"https:\/\/ajustica.net\/?p=2683"},"modified":"2024-11-14T17:44:18","modified_gmt":"2024-11-14T20:44:18","slug":"esquadroes-da-morte-assassinatos-de-jovens-em-luanda-causam-inseguranca-na-populacao","status":"publish","type":"post","link":"https:\/\/ajustica.net\/index.php\/2024\/11\/14\/esquadroes-da-morte-assassinatos-de-jovens-em-luanda-causam-inseguranca-na-populacao\/","title":{"rendered":"ESQUADR\u00d5ES DA MORTE: ASSASSINATOS DE JOVENS EM LUANDA CAUSAM INSEGURAN\u00c7A NA POPULA\u00c7\u00c3O"},"content":{"rendered":"\n<p>Foram a enterrar nesta quarta-feira, 13, no Cemit\u00e9rio do Benfica, em Luanda, Angola, dois dos tr\u00eas jovens encontrados mortos no s\u00e1bado, 9, nas proximidades do bairro Vila Kiaxi.<\/p>\n\n\n\n<p>Estes assassinatos levantam mais uma vez interroga\u00e7\u00f5es sobre o que est\u00e1 por tr\u00e1s da onda de mortes violentas na capital angolana.<\/p>\n\n\n\n<p>O porta-voz do Servi\u00e7o de Investiga\u00e7\u00e3o Criminal (SIC) n\u00e3o comentou os casos recentes, mas disse que a corpora\u00e7\u00e3o est\u00e1 a investigar.<\/p>\n\n\n\n<p>O aumento de homic\u00eddios em Luanda tem alarmado os moradores que apontam para a poss\u00edvel atua\u00e7\u00e3o de \u201cesquadr\u00f5es da morte\u201d, enquanto outros afirmam que essas mortes podem dever-se \u00e0 ades\u00e3o de jovens ao mundo do crime.Observadores admitem o envolvimento do crime organizado, disputas por controlo de territ\u00f3rios e ajustes de contas entre grupos.<\/p>\n\n\n\n<p>Nelson Francisco, presidente da Associa\u00e7\u00e3o de Jovens Resilientes, afirma n\u00e3o ter d\u00favidas que existe por tr\u00e1s destas mortes uma marca clara de crime organizado por conta de v\u00e1rios problemas sociais existentes no pa\u00eds.<\/p>\n\n\n\n<p>\u201cA pol\u00edcia, por si s\u00f3, n\u00e3o acreditamos n\u00f3s, ser\u00e1 capaz de p\u00f4r cobro a esta situa\u00e7\u00e3o\u201d, sustenta Francisco para quem \u201ca pol\u00edcia, por si s\u00f3, ser\u00e1 incapaz\u201d.<\/p>\n\n\n\n<p>Aquele activista social diz que \u00e9 necess\u00e1rio que &#8220;toda uma sociedade se una em volta dos problemas sociais que vivemos, para que possamos, ent\u00e3o, encontrar a solu\u00e7\u00e3o, para acabarmos ou minimizarmos o crescimento deste movimento\u201d.<\/p>\n\n\n\n<p>Nelson Francisco acrescenta ainda que devido \u201c\u00e0 precariedade social que hoje se vive, os jovens, maioritariamente, encontram-se envolvidos em determinados neg\u00f3cios que, por sua natureza, s\u00e3o de contornos dif\u00edceis e lament\u00e1vel e, na maior parte das vezes, com um fim tr\u00e1gico, como esses que a gente vai vivendo ou vai acompanhando no nosso dia a dia\u201d.<\/p>\n\n\n\n<p>Outra activista social, Evandra Furtunato, diz que s\u00f3 com investiga\u00e7\u00f5es profundas se podem esclarecer as raz\u00f5es dos assassinatos no pa\u00eds, mas reitera ser preocupante a impunidade que persiste.<\/p>\n\n\n\n<p>\u201cN\u00f3s, enquanto cidad\u00e3os, preocupamos-nos com a quest\u00e3o da impunidade\u201d, afirma Fortunato, que espera que &#8220;a pol\u00edcia possa fazer uma maior investiga\u00e7\u00e3o, possa prestar melhores esclarecimentos\u201d a esses casos.<\/p>\n\n\n\n<p>Contactado pela Voz da Am\u00e9rica, o porta-voz do SIC recusou-se a comentar as causas destas tr\u00eas mortes mais recentes, mas afirmou que o caso est\u00e1 em investiga\u00e7\u00e3o.<\/p>\n\n\n\n<p>\u201cO Servi\u00e7o de Investiga\u00e7\u00e3o Criminal tem miss\u00f5es pr\u00f3prias no \u00e2mbito da preven\u00e7\u00e3o e repress\u00e3o \u00e0 criminalidade. Sempre que ocorrem fatos criminais, sobretudo dessa natureza, no caso de homic\u00eddios, o que n\u00f3s fazemos \u00e9, portanto, abrir o competente procedimento criminal. Os cad\u00e1veres eventualmente encontrados s\u00e3o removidos para a per\u00edcia m\u00e9dico-legal ou a chamada inspe\u00e7\u00e3o m\u00e9dico-legal. E, determinadas as circunst\u00e2ncias da morte, avan\u00e7amos ent\u00e3o com a investiga\u00e7\u00e3o para a determina\u00e7\u00e3o da autoria material desses atos que jogam-nos a todos, jogam a sociedade\u201d, disse Manuel Halaiwa.<\/p>\n\n\n\n<p>Refira-se que, no m\u00eas de julho, foram encontrados corpos no Zango, no munic\u00edpio de Viana e nos munic\u00edpios de Cacuaco, Cazenga e Icolo e Bengo.<\/p>\n\n\n\n<p>H\u00e1 alguns anos, o investigador Rafael Marques denunciou a exist\u00eancia de execu\u00e7\u00f5es sum\u00e1rias em Luanda, atrav\u00e9s do relat\u00f3rio intitulado \u201cO Campo da Morte\u201d em que denunciava a exist\u00eancia de esquadr\u00f5es da morte Luanda.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Foram a enterrar nesta quarta-feira, 13, no Cemit\u00e9rio do Benfica, em Luanda, Angola, dois dos tr\u00eas jovens encontrados mortos no s\u00e1bado, 9, nas proximidades do bairro Vila Kiaxi. Estes assassinatos levantam mais uma vez interroga\u00e7\u00f5es sobre o que est\u00e1 por tr\u00e1s da onda de mortes violentas na capital angolana. O porta-voz do Servi\u00e7o de Investiga\u00e7\u00e3o [&hellip;]<\/p>\n","protected":false},"author":3,"featured_media":2684,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[2,4],"tags":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v20.10 - https:\/\/yoast.com\/wordpress\/plugins\/seo\/ -->\n<title>ESQUADR\u00d5ES DA MORTE: ASSASSINATOS DE JOVENS EM LUANDA CAUSAM INSEGURAN\u00c7A NA POPULA\u00c7\u00c3O -<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/ajustica.net\/index.php\/2024\/11\/14\/esquadroes-da-morte-assassinatos-de-jovens-em-luanda-causam-inseguranca-na-populacao\/\" \/>\n<meta property=\"og:locale\" content=\"pt_BR\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"ESQUADR\u00d5ES DA MORTE: ASSASSINATOS DE JOVENS EM LUANDA CAUSAM INSEGURAN\u00c7A NA POPULA\u00c7\u00c3O -\" \/>\n<meta property=\"og:description\" content=\"Foram a enterrar nesta quarta-feira, 13, no Cemit\u00e9rio do Benfica, em Luanda, Angola, dois dos tr\u00eas jovens encontrados mortos no s\u00e1bado, 9, nas proximidades do bairro Vila Kiaxi. Estes assassinatos levantam mais uma vez interroga\u00e7\u00f5es sobre o que est\u00e1 por tr\u00e1s da onda de mortes violentas na capital angolana. O porta-voz do Servi\u00e7o de Investiga\u00e7\u00e3o [&hellip;]\" \/>\n<meta property=\"og:url\" content=\"https:\/\/ajustica.net\/index.php\/2024\/11\/14\/esquadroes-da-morte-assassinatos-de-jovens-em-luanda-causam-inseguranca-na-populacao\/\" \/>\n<meta property=\"article:published_time\" content=\"2024-11-14T20:44:17+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2024-11-14T20:44:18+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/ajustica.net\/wp-content\/uploads\/2024\/11\/transferir-8-1.jpeg\" \/>\n\t<meta property=\"og:image:width\" content=\"526\" \/>\n\t<meta property=\"og:image:height\" content=\"289\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"author\" content=\"Portal Justi\u00e7a\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Escrito por\" \/>\n\t<meta name=\"twitter:data1\" content=\"Portal Justi\u00e7a\" \/>\n\t<meta name=\"twitter:label2\" content=\"Est. tempo de leitura\" \/>\n\t<meta name=\"twitter:data2\" content=\"3 minutos\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\/\/schema.org\",\"@graph\":[{\"@type\":\"WebPage\",\"@id\":\"https:\/\/ajustica.net\/index.php\/2024\/11\/14\/esquadroes-da-morte-assassinatos-de-jovens-em-luanda-causam-inseguranca-na-populacao\/\",\"url\":\"https:\/\/ajustica.net\/index.php\/2024\/11\/14\/esquadroes-da-morte-assassinatos-de-jovens-em-luanda-causam-inseguranca-na-populacao\/\",\"name\":\"ESQUADR\u00d5ES DA MORTE: ASSASSINATOS DE JOVENS EM LUANDA CAUSAM INSEGURAN\u00c7A NA POPULA\u00c7\u00c3O -\",\"isPartOf\":{\"@id\":\"https:\/\/ajustica.net\/#website\"},\"datePublished\":\"2024-11-14T20:44:17+00:00\",\"dateModified\":\"2024-11-14T20:44:18+00:00\",\"author\":{\"@id\":\"https:\/\/ajustica.net\/#\/schema\/person\/e1f71ed49e0f63898db2951a6b747d62\"},\"breadcrumb\":{\"@id\":\"https:\/\/ajustica.net\/index.php\/2024\/11\/14\/esquadroes-da-morte-assassinatos-de-jovens-em-luanda-causam-inseguranca-na-populacao\/#breadcrumb\"},\"inLanguage\":\"pt-BR\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\/\/ajustica.net\/index.php\/2024\/11\/14\/esquadroes-da-morte-assassinatos-de-jovens-em-luanda-causam-inseguranca-na-populacao\/\"]}]},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\/\/ajustica.net\/index.php\/2024\/11\/14\/esquadroes-da-morte-assassinatos-de-jovens-em-luanda-causam-inseguranca-na-populacao\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"In\u00edcio\",\"item\":\"https:\/\/ajustica.net\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"ESQUADR\u00d5ES DA MORTE: ASSASSINATOS DE JOVENS EM LUANDA CAUSAM INSEGURAN\u00c7A NA POPULA\u00c7\u00c3O\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\/\/ajustica.net\/#website\",\"url\":\"https:\/\/ajustica.net\/\",\"name\":\"\",\"description\":\"Email Para Den\u00fancia: ajusticaa@gmail.com\",\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\/\/ajustica.net\/?s={search_term_string}\"},\"query-input\":\"required name=search_term_string\"}],\"inLanguage\":\"pt-BR\"},{\"@type\":\"Person\",\"@id\":\"https:\/\/ajustica.net\/#\/schema\/person\/e1f71ed49e0f63898db2951a6b747d62\",\"name\":\"Portal Justi\u00e7a\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"pt-BR\",\"@id\":\"https:\/\/ajustica.net\/#\/schema\/person\/image\/\",\"url\":\"https:\/\/secure.gravatar.com\/avatar\/14c19bb3bbce6a73ddabbf74322a5807?s=96&d=mm&r=g\",\"contentUrl\":\"https:\/\/secure.gravatar.com\/avatar\/14c19bb3bbce6a73ddabbf74322a5807?s=96&d=mm&r=g\",\"caption\":\"Portal Justi\u00e7a\"},\"url\":\"https:\/\/ajustica.net\/index.php\/author\/justica\/\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"ESQUADR\u00d5ES DA MORTE: ASSASSINATOS DE JOVENS EM LUANDA CAUSAM INSEGURAN\u00c7A NA POPULA\u00c7\u00c3O -","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/ajustica.net\/index.php\/2024\/11\/14\/esquadroes-da-morte-assassinatos-de-jovens-em-luanda-causam-inseguranca-na-populacao\/","og_locale":"pt_BR","og_type":"article","og_title":"ESQUADR\u00d5ES DA MORTE: ASSASSINATOS DE JOVENS EM LUANDA CAUSAM INSEGURAN\u00c7A NA POPULA\u00c7\u00c3O -","og_description":"Foram a enterrar nesta quarta-feira, 13, no Cemit\u00e9rio do Benfica, em Luanda, Angola, dois dos tr\u00eas jovens encontrados mortos no s\u00e1bado, 9, nas proximidades do bairro Vila Kiaxi. Estes assassinatos levantam mais uma vez interroga\u00e7\u00f5es sobre o que est\u00e1 por tr\u00e1s da onda de mortes violentas na capital angolana. O porta-voz do Servi\u00e7o de Investiga\u00e7\u00e3o [&hellip;]","og_url":"https:\/\/ajustica.net\/index.php\/2024\/11\/14\/esquadroes-da-morte-assassinatos-de-jovens-em-luanda-causam-inseguranca-na-populacao\/","article_published_time":"2024-11-14T20:44:17+00:00","article_modified_time":"2024-11-14T20:44:18+00:00","og_image":[{"width":526,"height":289,"url":"https:\/\/ajustica.net\/wp-content\/uploads\/2024\/11\/transferir-8-1.jpeg","type":"image\/jpeg"}],"author":"Portal Justi\u00e7a","twitter_card":"summary_large_image","twitter_misc":{"Escrito por":"Portal Justi\u00e7a","Est. tempo de leitura":"3 minutos"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"WebPage","@id":"https:\/\/ajustica.net\/index.php\/2024\/11\/14\/esquadroes-da-morte-assassinatos-de-jovens-em-luanda-causam-inseguranca-na-populacao\/","url":"https:\/\/ajustica.net\/index.php\/2024\/11\/14\/esquadroes-da-morte-assassinatos-de-jovens-em-luanda-causam-inseguranca-na-populacao\/","name":"ESQUADR\u00d5ES DA MORTE: ASSASSINATOS DE JOVENS EM LUANDA CAUSAM INSEGURAN\u00c7A NA POPULA\u00c7\u00c3O -","isPartOf":{"@id":"https:\/\/ajustica.net\/#website"},"datePublished":"2024-11-14T20:44:17+00:00","dateModified":"2024-11-14T20:44:18+00:00","author":{"@id":"https:\/\/ajustica.net\/#\/schema\/person\/e1f71ed49e0f63898db2951a6b747d62"},"breadcrumb":{"@id":"https:\/\/ajustica.net\/index.php\/2024\/11\/14\/esquadroes-da-morte-assassinatos-de-jovens-em-luanda-causam-inseguranca-na-populacao\/#breadcrumb"},"inLanguage":"pt-BR","potentialAction":[{"@type":"ReadAction","target":["https:\/\/ajustica.net\/index.php\/2024\/11\/14\/esquadroes-da-morte-assassinatos-de-jovens-em-luanda-causam-inseguranca-na-populacao\/"]}]},{"@type":"BreadcrumbList","@id":"https:\/\/ajustica.net\/index.php\/2024\/11\/14\/esquadroes-da-morte-assassinatos-de-jovens-em-luanda-causam-inseguranca-na-populacao\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"In\u00edcio","item":"https:\/\/ajustica.net\/"},{"@type":"ListItem","position":2,"name":"ESQUADR\u00d5ES DA MORTE: ASSASSINATOS DE JOVENS EM LUANDA CAUSAM INSEGURAN\u00c7A NA POPULA\u00c7\u00c3O"}]},{"@type":"WebSite","@id":"https:\/\/ajustica.net\/#website","url":"https:\/\/ajustica.net\/","name":"","description":"Email Para Den\u00fancia: ajusticaa@gmail.com","potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/ajustica.net\/?s={search_term_string}"},"query-input":"required name=search_term_string"}],"inLanguage":"pt-BR"},{"@type":"Person","@id":"https:\/\/ajustica.net\/#\/schema\/person\/e1f71ed49e0f63898db2951a6b747d62","name":"Portal Justi\u00e7a","image":{"@type":"ImageObject","inLanguage":"pt-BR","@id":"https:\/\/ajustica.net\/#\/schema\/person\/image\/","url":"https:\/\/secure.gravatar.com\/avatar\/14c19bb3bbce6a73ddabbf74322a5807?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/14c19bb3bbce6a73ddabbf74322a5807?s=96&d=mm&r=g","caption":"Portal Justi\u00e7a"},"url":"https:\/\/ajustica.net\/index.php\/author\/justica\/"}]}},"_links":{"self":[{"href":"https:\/\/ajustica.net\/index.php\/wp-json\/wp\/v2\/posts\/2683"}],"collection":[{"href":"https:\/\/ajustica.net\/index.php\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/ajustica.net\/index.php\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/ajustica.net\/index.php\/wp-json\/wp\/v2\/users\/3"}],"replies":[{"embeddable":true,"href":"https:\/\/ajustica.net\/index.php\/wp-json\/wp\/v2\/comments?post=2683"}],"version-history":[{"count":1,"href":"https:\/\/ajustica.net\/index.php\/wp-json\/wp\/v2\/posts\/2683\/revisions"}],"predecessor-version":[{"id":2685,"href":"https:\/\/ajustica.net\/index.php\/wp-json\/wp\/v2\/posts\/2683\/revisions\/2685"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/ajustica.net\/index.php\/wp-json\/wp\/v2\/media\/2684"}],"wp:attachment":[{"href":"https:\/\/ajustica.net\/index.php\/wp-json\/wp\/v2\/media?parent=2683"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/ajustica.net\/index.php\/wp-json\/wp\/v2\/categories?post=2683"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/ajustica.net\/index.php\/wp-json\/wp\/v2\/tags?post=2683"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}