{"id":2104,"date":"2024-07-12T09:02:13","date_gmt":"2024-07-12T12:02:13","guid":{"rendered":"https:\/\/ajustica.net\/?p=2104"},"modified":"2024-07-12T09:02:17","modified_gmt":"2024-07-12T12:02:17","slug":"pgr-menos-actuante-rosa-pacavira-e-o-seu-marido-abilio-gaspar-acusados-de-golpistas-que-deveriam-ser-julgada","status":"publish","type":"post","link":"https:\/\/ajustica.net\/index.php\/2024\/07\/12\/pgr-menos-actuante-rosa-pacavira-e-o-seu-marido-abilio-gaspar-acusados-de-golpistas-que-deveriam-ser-julgada\/","title":{"rendered":"PGR MENOS ACTUANTE: ROSA PACAVIRA E O SEU MARIDO AB\u00cdLIO GASPAR ACUSADOS DE GOLPISTAS QUE DEVERIAM SER JULGADA"},"content":{"rendered":"\n<p>Quando \u00e9 que a Procuradoria-Geral da Rep\u00fablica (PGR) se vai pronunciar acerca das acusa\u00e7\u00f5es contra a ex-ministra do Com\u00e9rcio, Rosa Pacavira de Matos, que delapidou, com o marido, Abilio Gaspar, o Minist\u00e9rio do Com\u00e9rcio (Minco)? Os angolanos j\u00e1 est\u00e3o cansados de questionar a raz\u00e3o que faz com que Rosa Pacavira continue serenamente a beneficiar de tudo quanto roubou ao Estado. Ser\u00e1 porque sempre foi a protegida do ex \u2013 Procurador Jo\u00e3o Maria de Sousa?<\/p>\n\n\n\n<p>Segundo consta, quando foi nomeada por Jos\u00e9 Eduardo dos Santos para ministra do Com\u00e9rcio, menos de dois anos Rosa Pacavira fez uma casa de luxo ao p\u00e9 do Comit\u00e9 Provincial do MPLA, comprou uma casa onde vive no Para\u00edso Real, apartamentos nas Torres Dipanda, Pal\u00e1cio no Nova Vida, Casa Royal Park, Casas Camama, apartamentos de luxo na Ilha de Luanda, quintas em Bom Jesus e Km 30 (constru\u00e7\u00f5es feitas pelas empresas CLOD, um cons\u00f3rcio luso-espanhol), carros de luxo topo de gama, mais caros para todos filhos e sobrinhos, alguns dados pelo indiano que ficou com os armaz\u00e9ns todos do CLOD e outro angolano, para al\u00e9m de apartamentos em Lisboa e contas nas Mauricias, India e Istambul.<\/p>\n\n\n\n<p>Atrav\u00e9s da empresa Concentra, pagou avultadas comiss\u00f5es e mobilou as casas dela, filhos, familiares e afilhados, tudo pago pelo Minist\u00e9rio do Com\u00e9rcio (Minco) que dirigia.<\/p>\n\n\n\n<p>Delapidou o Papagro, Kuia (cart\u00f5es eram entregues a familiares e amigos), e ao cons\u00f3rcio CLOD, pagou milh\u00f5es em comiss\u00f5es para construir todas as lojas, de que se apoderou e distribuiu a familiares e amigos.<\/p>\n\n\n\n<p>No bairro da Coreia, transformou a casa da sogra numa loja \u201cPaparoca\u201d, reconstruiu a casa toda e fez um pr\u00e9dio, tudo pago pelo Minco.<\/p>\n\n\n\n<p>O entreposto foi saqueado por Jofre Van-d\u00fanem, seu primo; o seu irm\u00e3o no CLOD roubou at\u00e9 n\u00e3o poder mais; encheu o Minco com a familia e noras.&nbsp;<\/p>\n\n\n\n<p>Ao seu \u201ctesta de ferro\u201d e do primo Jofre Van-d\u00fanen, Porf\u00edrio, deu uma casa avaliada em 3 milh\u00f5es de d\u00f3lares. O indiv\u00edduo s\u00f3 usa Luis Vuiton e Gucci Armani como ela. A secret\u00e1ria dela sabe tudo e \u00e9 sua c\u00famplice.<\/p>\n\n\n\n<p>Porfirio trabalha com ela desde que era secret\u00e1ria dos Assuntos Sociais e ajudou-a a roubar na presid\u00eancia e no Minist\u00e9rio. O ministro Jofre Van-d\u00fanen, primo dela, foi buscar Profirio para continuar a ladroagem no Minist\u00e9rio.<\/p>\n\n\n\n<p>Jos\u00e9 Esuardo dos Santos, quando descobriu a verdade correu com ela e o processo foi para a PGR, mas o ent\u00e3o procurador, Jo\u00e3o Maria de Sousa, abafou o processo porque s\u00e3o primos. Miluxa Abrantes deixou a Apiex toda mobilada e nova, deixou milh\u00f5es nos cofres da Apiex e Rosa Pacavira delapidou tudo em 15 dias.<\/p>\n\n\n\n<p>Chamou a decoradora da Concentra e mudou tudo, at\u00e9 quadros, loi\u00e7as desapareceram e gastou uma fortuna a mobilar a Apiex. Henriques da Silva e Belarmin Van-d\u00fanem nunca mais souberam para onde foram tais mobilias.<\/p>\n\n\n\n<p>Era protegida de Avelino dos Santos, mas JES ficou bravo com ela, nunca mais lhe dirigiu a palavra e retirou-a de todos os cargos.<\/p>\n\n\n\n<p>Depois da retirada de JES, tentou bajular Jo\u00e3o Louren\u00e7o e a Primeira Dama, Ana Dias Louren\u00e7o, mas estes, por saberem quem ela \u00e9, mandaram-na bugiar.<\/p>\n\n\n\n<p>N\u00e3o \u00e9 benquista entre antigos colegas porque tratava mal a todos, menos a quem lhe interessava. Nos pa\u00edses que visitou, exigia aos Embaixadores jantares em sua honra. Prepotente, sem educa\u00e7\u00e3o, muito grosseira com todos funcion\u00e1rios, subiu muito, mas ca\u00edu r\u00e1pido, por\u00e9m roubou quanto baste e ajudou a atirar o pa\u00eds para o abismo da desgra\u00e7a.<\/p>\n\n\n\n<p>A PGR tem que pegar no seu processo rapidamente, antes que o \u201cgato\u201d escape, como j\u00e1 tem acontecido com muitos outros lar\u00e1pios!<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Quando \u00e9 que a Procuradoria-Geral da Rep\u00fablica (PGR) se vai pronunciar acerca das acusa\u00e7\u00f5es contra a ex-ministra do Com\u00e9rcio, Rosa Pacavira de Matos, que delapidou, com o marido, Abilio Gaspar, o Minist\u00e9rio do Com\u00e9rcio (Minco)? Os angolanos j\u00e1 est\u00e3o cansados de questionar a raz\u00e3o que faz com que Rosa Pacavira continue serenamente a beneficiar de [&hellip;]<\/p>\n","protected":false},"author":3,"featured_media":2105,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[3,2],"tags":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v20.10 - https:\/\/yoast.com\/wordpress\/plugins\/seo\/ -->\n<title>PGR MENOS ACTUANTE: ROSA PACAVIRA E O SEU MARIDO AB\u00cdLIO GASPAR ACUSADOS DE GOLPISTAS QUE DEVERIAM SER JULGADA -<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/ajustica.net\/index.php\/2024\/07\/12\/pgr-menos-actuante-rosa-pacavira-e-o-seu-marido-abilio-gaspar-acusados-de-golpistas-que-deveriam-ser-julgada\/\" \/>\n<meta property=\"og:locale\" content=\"pt_BR\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"PGR MENOS ACTUANTE: ROSA PACAVIRA E O SEU MARIDO AB\u00cdLIO GASPAR ACUSADOS DE GOLPISTAS QUE DEVERIAM SER JULGADA -\" \/>\n<meta property=\"og:description\" content=\"Quando \u00e9 que a Procuradoria-Geral da Rep\u00fablica (PGR) se vai pronunciar acerca das acusa\u00e7\u00f5es contra a ex-ministra do Com\u00e9rcio, Rosa Pacavira de Matos, que delapidou, com o marido, Abilio Gaspar, o Minist\u00e9rio do Com\u00e9rcio (Minco)? Os angolanos j\u00e1 est\u00e3o cansados de questionar a raz\u00e3o que faz com que Rosa Pacavira continue serenamente a beneficiar de [&hellip;]\" \/>\n<meta property=\"og:url\" content=\"https:\/\/ajustica.net\/index.php\/2024\/07\/12\/pgr-menos-actuante-rosa-pacavira-e-o-seu-marido-abilio-gaspar-acusados-de-golpistas-que-deveriam-ser-julgada\/\" \/>\n<meta property=\"article:published_time\" content=\"2024-07-12T12:02:13+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2024-07-12T12:02:17+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/ajustica.net\/wp-content\/uploads\/2024\/07\/transferir-2.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"246\" \/>\n\t<meta property=\"og:image:height\" content=\"163\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"author\" content=\"Portal Justi\u00e7a\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Escrito por\" \/>\n\t<meta name=\"twitter:data1\" content=\"Portal Justi\u00e7a\" \/>\n\t<meta name=\"twitter:label2\" content=\"Est. tempo de leitura\" \/>\n\t<meta name=\"twitter:data2\" content=\"4 minutos\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\/\/schema.org\",\"@graph\":[{\"@type\":\"WebPage\",\"@id\":\"https:\/\/ajustica.net\/index.php\/2024\/07\/12\/pgr-menos-actuante-rosa-pacavira-e-o-seu-marido-abilio-gaspar-acusados-de-golpistas-que-deveriam-ser-julgada\/\",\"url\":\"https:\/\/ajustica.net\/index.php\/2024\/07\/12\/pgr-menos-actuante-rosa-pacavira-e-o-seu-marido-abilio-gaspar-acusados-de-golpistas-que-deveriam-ser-julgada\/\",\"name\":\"PGR MENOS ACTUANTE: ROSA PACAVIRA E O SEU MARIDO AB\u00cdLIO GASPAR ACUSADOS DE GOLPISTAS QUE DEVERIAM SER JULGADA -\",\"isPartOf\":{\"@id\":\"https:\/\/ajustica.net\/#website\"},\"datePublished\":\"2024-07-12T12:02:13+00:00\",\"dateModified\":\"2024-07-12T12:02:17+00:00\",\"author\":{\"@id\":\"https:\/\/ajustica.net\/#\/schema\/person\/e1f71ed49e0f63898db2951a6b747d62\"},\"breadcrumb\":{\"@id\":\"https:\/\/ajustica.net\/index.php\/2024\/07\/12\/pgr-menos-actuante-rosa-pacavira-e-o-seu-marido-abilio-gaspar-acusados-de-golpistas-que-deveriam-ser-julgada\/#breadcrumb\"},\"inLanguage\":\"pt-BR\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\/\/ajustica.net\/index.php\/2024\/07\/12\/pgr-menos-actuante-rosa-pacavira-e-o-seu-marido-abilio-gaspar-acusados-de-golpistas-que-deveriam-ser-julgada\/\"]}]},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\/\/ajustica.net\/index.php\/2024\/07\/12\/pgr-menos-actuante-rosa-pacavira-e-o-seu-marido-abilio-gaspar-acusados-de-golpistas-que-deveriam-ser-julgada\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"In\u00edcio\",\"item\":\"https:\/\/ajustica.net\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"PGR MENOS ACTUANTE: ROSA PACAVIRA E O SEU MARIDO AB\u00cdLIO GASPAR ACUSADOS DE GOLPISTAS QUE DEVERIAM SER JULGADA\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\/\/ajustica.net\/#website\",\"url\":\"https:\/\/ajustica.net\/\",\"name\":\"\",\"description\":\"Email Para Den\u00fancia: ajusticaa@gmail.com\",\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\/\/ajustica.net\/?s={search_term_string}\"},\"query-input\":\"required name=search_term_string\"}],\"inLanguage\":\"pt-BR\"},{\"@type\":\"Person\",\"@id\":\"https:\/\/ajustica.net\/#\/schema\/person\/e1f71ed49e0f63898db2951a6b747d62\",\"name\":\"Portal Justi\u00e7a\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"pt-BR\",\"@id\":\"https:\/\/ajustica.net\/#\/schema\/person\/image\/\",\"url\":\"https:\/\/secure.gravatar.com\/avatar\/14c19bb3bbce6a73ddabbf74322a5807?s=96&d=mm&r=g\",\"contentUrl\":\"https:\/\/secure.gravatar.com\/avatar\/14c19bb3bbce6a73ddabbf74322a5807?s=96&d=mm&r=g\",\"caption\":\"Portal Justi\u00e7a\"},\"url\":\"https:\/\/ajustica.net\/index.php\/author\/justica\/\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"PGR MENOS ACTUANTE: ROSA PACAVIRA E O SEU MARIDO AB\u00cdLIO GASPAR ACUSADOS DE GOLPISTAS QUE DEVERIAM SER JULGADA -","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/ajustica.net\/index.php\/2024\/07\/12\/pgr-menos-actuante-rosa-pacavira-e-o-seu-marido-abilio-gaspar-acusados-de-golpistas-que-deveriam-ser-julgada\/","og_locale":"pt_BR","og_type":"article","og_title":"PGR MENOS ACTUANTE: ROSA PACAVIRA E O SEU MARIDO AB\u00cdLIO GASPAR ACUSADOS DE GOLPISTAS QUE DEVERIAM SER JULGADA -","og_description":"Quando \u00e9 que a Procuradoria-Geral da Rep\u00fablica (PGR) se vai pronunciar acerca das acusa\u00e7\u00f5es contra a ex-ministra do Com\u00e9rcio, Rosa Pacavira de Matos, que delapidou, com o marido, Abilio Gaspar, o Minist\u00e9rio do Com\u00e9rcio (Minco)? Os angolanos j\u00e1 est\u00e3o cansados de questionar a raz\u00e3o que faz com que Rosa Pacavira continue serenamente a beneficiar de [&hellip;]","og_url":"https:\/\/ajustica.net\/index.php\/2024\/07\/12\/pgr-menos-actuante-rosa-pacavira-e-o-seu-marido-abilio-gaspar-acusados-de-golpistas-que-deveriam-ser-julgada\/","article_published_time":"2024-07-12T12:02:13+00:00","article_modified_time":"2024-07-12T12:02:17+00:00","og_image":[{"width":246,"height":163,"url":"https:\/\/ajustica.net\/wp-content\/uploads\/2024\/07\/transferir-2.jpg","type":"image\/jpeg"}],"author":"Portal Justi\u00e7a","twitter_card":"summary_large_image","twitter_misc":{"Escrito por":"Portal Justi\u00e7a","Est. tempo de leitura":"4 minutos"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"WebPage","@id":"https:\/\/ajustica.net\/index.php\/2024\/07\/12\/pgr-menos-actuante-rosa-pacavira-e-o-seu-marido-abilio-gaspar-acusados-de-golpistas-que-deveriam-ser-julgada\/","url":"https:\/\/ajustica.net\/index.php\/2024\/07\/12\/pgr-menos-actuante-rosa-pacavira-e-o-seu-marido-abilio-gaspar-acusados-de-golpistas-que-deveriam-ser-julgada\/","name":"PGR MENOS ACTUANTE: ROSA PACAVIRA E O SEU MARIDO AB\u00cdLIO GASPAR ACUSADOS DE GOLPISTAS QUE DEVERIAM SER JULGADA -","isPartOf":{"@id":"https:\/\/ajustica.net\/#website"},"datePublished":"2024-07-12T12:02:13+00:00","dateModified":"2024-07-12T12:02:17+00:00","author":{"@id":"https:\/\/ajustica.net\/#\/schema\/person\/e1f71ed49e0f63898db2951a6b747d62"},"breadcrumb":{"@id":"https:\/\/ajustica.net\/index.php\/2024\/07\/12\/pgr-menos-actuante-rosa-pacavira-e-o-seu-marido-abilio-gaspar-acusados-de-golpistas-que-deveriam-ser-julgada\/#breadcrumb"},"inLanguage":"pt-BR","potentialAction":[{"@type":"ReadAction","target":["https:\/\/ajustica.net\/index.php\/2024\/07\/12\/pgr-menos-actuante-rosa-pacavira-e-o-seu-marido-abilio-gaspar-acusados-de-golpistas-que-deveriam-ser-julgada\/"]}]},{"@type":"BreadcrumbList","@id":"https:\/\/ajustica.net\/index.php\/2024\/07\/12\/pgr-menos-actuante-rosa-pacavira-e-o-seu-marido-abilio-gaspar-acusados-de-golpistas-que-deveriam-ser-julgada\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"In\u00edcio","item":"https:\/\/ajustica.net\/"},{"@type":"ListItem","position":2,"name":"PGR MENOS ACTUANTE: ROSA PACAVIRA E O SEU MARIDO AB\u00cdLIO GASPAR ACUSADOS DE GOLPISTAS QUE DEVERIAM SER JULGADA"}]},{"@type":"WebSite","@id":"https:\/\/ajustica.net\/#website","url":"https:\/\/ajustica.net\/","name":"","description":"Email Para Den\u00fancia: ajusticaa@gmail.com","potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/ajustica.net\/?s={search_term_string}"},"query-input":"required name=search_term_string"}],"inLanguage":"pt-BR"},{"@type":"Person","@id":"https:\/\/ajustica.net\/#\/schema\/person\/e1f71ed49e0f63898db2951a6b747d62","name":"Portal Justi\u00e7a","image":{"@type":"ImageObject","inLanguage":"pt-BR","@id":"https:\/\/ajustica.net\/#\/schema\/person\/image\/","url":"https:\/\/secure.gravatar.com\/avatar\/14c19bb3bbce6a73ddabbf74322a5807?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/14c19bb3bbce6a73ddabbf74322a5807?s=96&d=mm&r=g","caption":"Portal Justi\u00e7a"},"url":"https:\/\/ajustica.net\/index.php\/author\/justica\/"}]}},"_links":{"self":[{"href":"https:\/\/ajustica.net\/index.php\/wp-json\/wp\/v2\/posts\/2104"}],"collection":[{"href":"https:\/\/ajustica.net\/index.php\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/ajustica.net\/index.php\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/ajustica.net\/index.php\/wp-json\/wp\/v2\/users\/3"}],"replies":[{"embeddable":true,"href":"https:\/\/ajustica.net\/index.php\/wp-json\/wp\/v2\/comments?post=2104"}],"version-history":[{"count":1,"href":"https:\/\/ajustica.net\/index.php\/wp-json\/wp\/v2\/posts\/2104\/revisions"}],"predecessor-version":[{"id":2106,"href":"https:\/\/ajustica.net\/index.php\/wp-json\/wp\/v2\/posts\/2104\/revisions\/2106"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/ajustica.net\/index.php\/wp-json\/wp\/v2\/media\/2105"}],"wp:attachment":[{"href":"https:\/\/ajustica.net\/index.php\/wp-json\/wp\/v2\/media?parent=2104"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/ajustica.net\/index.php\/wp-json\/wp\/v2\/categories?post=2104"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/ajustica.net\/index.php\/wp-json\/wp\/v2\/tags?post=2104"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}