{"id":1446,"date":"2024-03-13T13:36:33","date_gmt":"2024-03-13T16:36:33","guid":{"rendered":"https:\/\/ajustica.net\/?p=1446"},"modified":"2024-03-13T13:36:34","modified_gmt":"2024-03-13T16:36:34","slug":"mwangai-e-a-historia-gerson-prata","status":"publish","type":"post","link":"https:\/\/ajustica.net\/index.php\/2024\/03\/13\/mwangai-e-a-historia-gerson-prata\/","title":{"rendered":"MWANGAI E A HIST\u00d3RIA &#8211; GERSON PRATA"},"content":{"rendered":"\n<p>&nbsp;A hist\u00f3ria de verdade e da verdade n\u00e3o morre e n\u00e3o se apaga. E a verdade \u00e9 que existem localidades que, devido a sua import\u00e2ncia e simbolismo, est\u00e3o ligadas \u00e0 mem\u00f3ria colectiva de determinados povos ou grupos de pessoas que comungam do mesmo ide\u00e1rio Pol\u00edtico. \u00c9 agir de m\u00e1 f\u00e9 inventar artif\u00edcios para apagar essas mem\u00f3rias.<\/p>\n\n\n\n<p>POR: A JUSTI\u00c7A<\/p>\n\n\n\n<p>A constru\u00e7\u00e3o da na\u00e7\u00e3o angolana passa pelo respeito escrupuloso da identidade e dos s\u00edmbolos identit\u00e1rios dos povos que habitam o territ\u00f3rio que se chama Angola. Relegar Mwangai, independentemente da argumenta\u00e7\u00e3o, \u00e9 o mesmo que tentar apagar parte significativa da hist\u00f3ria da luta anti-colonial; \u00e9, tamb\u00e9m, uma demonstra\u00e7\u00e3o ostensiva de abuso de confian\u00e7a e, sobretudo, um acto de extrema intoler\u00e2ncia pol\u00edtica e cultural. Mwangai n\u00e3o pode ser tratado de qualquer maneira. A hist\u00f3ria da independ\u00eancia de Angola passou tamb\u00e9m por Mwangai. O Estado Democr\u00e1tico de Direito foi uma imposi\u00e7\u00e3o do Projecto Mwangai. S\u00f3 esses dois factos deveriam ser suficientes para se preservar MWANGAI com todas as suas letras no Mapa de Angola. Ali\u00e1s, Mwangai \u00e9 a \u00fanica localidade do Pa\u00eds onde foi fundado um dos tr\u00eas movimentos de liberta\u00e7\u00e3o nacional.<\/p>\n\n\n\n<p>&nbsp;Como ainda estamos na fase de consulta p\u00fablica, tenho f\u00e9 de que os patriotas e nacionalistas do MPLA n\u00e3o v\u00e3o deixar que se avance com isto; e alguma coisa me diz que o povo cokwe, da mesma forma que reprovou o nome de Kasai, para a nova prov\u00edncia do Moxico, haver\u00e1 de dizer n\u00e3o \u00e0 inten\u00e7\u00e3o de se mudar um nome secular deixado pelos seus ancestrais &#8211; MWANGAI.<\/p>\n\n\n\n<p>&nbsp;&#8220;N\u00e3o h\u00e1 futuro para um povo que nega seu passado&#8221; &#8211; Mosiah Garvey<\/p>\n\n\n\n<p>Gerson Prata<\/p>\n","protected":false},"excerpt":{"rendered":"<p>&nbsp;A hist\u00f3ria de verdade e da verdade n\u00e3o morre e n\u00e3o se apaga. E a verdade \u00e9 que existem localidades que, devido a sua import\u00e2ncia e simbolismo, est\u00e3o ligadas \u00e0 mem\u00f3ria colectiva de determinados povos ou grupos de pessoas que comungam do mesmo ide\u00e1rio Pol\u00edtico. \u00c9 agir de m\u00e1 f\u00e9 inventar artif\u00edcios para apagar essas [&hellip;]<\/p>\n","protected":false},"author":3,"featured_media":1447,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[2,5],"tags":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v20.10 - https:\/\/yoast.com\/wordpress\/plugins\/seo\/ -->\n<title>MWANGAI E A HIST\u00d3RIA - GERSON PRATA -<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/ajustica.net\/index.php\/2024\/03\/13\/mwangai-e-a-historia-gerson-prata\/\" \/>\n<meta property=\"og:locale\" content=\"pt_BR\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"MWANGAI E A HIST\u00d3RIA - GERSON PRATA -\" \/>\n<meta property=\"og:description\" content=\"&nbsp;A hist\u00f3ria de verdade e da verdade n\u00e3o morre e n\u00e3o se apaga. E a verdade \u00e9 que existem localidades que, devido a sua import\u00e2ncia e simbolismo, est\u00e3o ligadas \u00e0 mem\u00f3ria colectiva de determinados povos ou grupos de pessoas que comungam do mesmo ide\u00e1rio Pol\u00edtico. \u00c9 agir de m\u00e1 f\u00e9 inventar artif\u00edcios para apagar essas [&hellip;]\" \/>\n<meta property=\"og:url\" content=\"https:\/\/ajustica.net\/index.php\/2024\/03\/13\/mwangai-e-a-historia-gerson-prata\/\" \/>\n<meta property=\"article:published_time\" content=\"2024-03-13T16:36:33+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2024-03-13T16:36:34+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/ajustica.net\/wp-content\/uploads\/2024\/03\/jonasvalentim.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"960\" \/>\n\t<meta property=\"og:image:height\" content=\"720\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"author\" content=\"Portal Justi\u00e7a\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Escrito por\" \/>\n\t<meta name=\"twitter:data1\" content=\"Portal Justi\u00e7a\" \/>\n\t<meta name=\"twitter:label2\" content=\"Est. tempo de leitura\" \/>\n\t<meta name=\"twitter:data2\" content=\"2 minutos\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\/\/schema.org\",\"@graph\":[{\"@type\":\"WebPage\",\"@id\":\"https:\/\/ajustica.net\/index.php\/2024\/03\/13\/mwangai-e-a-historia-gerson-prata\/\",\"url\":\"https:\/\/ajustica.net\/index.php\/2024\/03\/13\/mwangai-e-a-historia-gerson-prata\/\",\"name\":\"MWANGAI E A HIST\u00d3RIA - GERSON PRATA -\",\"isPartOf\":{\"@id\":\"https:\/\/ajustica.net\/#website\"},\"datePublished\":\"2024-03-13T16:36:33+00:00\",\"dateModified\":\"2024-03-13T16:36:34+00:00\",\"author\":{\"@id\":\"https:\/\/ajustica.net\/#\/schema\/person\/e1f71ed49e0f63898db2951a6b747d62\"},\"breadcrumb\":{\"@id\":\"https:\/\/ajustica.net\/index.php\/2024\/03\/13\/mwangai-e-a-historia-gerson-prata\/#breadcrumb\"},\"inLanguage\":\"pt-BR\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\/\/ajustica.net\/index.php\/2024\/03\/13\/mwangai-e-a-historia-gerson-prata\/\"]}]},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\/\/ajustica.net\/index.php\/2024\/03\/13\/mwangai-e-a-historia-gerson-prata\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"In\u00edcio\",\"item\":\"https:\/\/ajustica.net\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"MWANGAI E A HIST\u00d3RIA &#8211; GERSON PRATA\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\/\/ajustica.net\/#website\",\"url\":\"https:\/\/ajustica.net\/\",\"name\":\"\",\"description\":\"Email Para Den\u00fancia: ajusticaa@gmail.com\",\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\/\/ajustica.net\/?s={search_term_string}\"},\"query-input\":\"required name=search_term_string\"}],\"inLanguage\":\"pt-BR\"},{\"@type\":\"Person\",\"@id\":\"https:\/\/ajustica.net\/#\/schema\/person\/e1f71ed49e0f63898db2951a6b747d62\",\"name\":\"Portal Justi\u00e7a\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"pt-BR\",\"@id\":\"https:\/\/ajustica.net\/#\/schema\/person\/image\/\",\"url\":\"https:\/\/secure.gravatar.com\/avatar\/14c19bb3bbce6a73ddabbf74322a5807?s=96&d=mm&r=g\",\"contentUrl\":\"https:\/\/secure.gravatar.com\/avatar\/14c19bb3bbce6a73ddabbf74322a5807?s=96&d=mm&r=g\",\"caption\":\"Portal Justi\u00e7a\"},\"url\":\"https:\/\/ajustica.net\/index.php\/author\/justica\/\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"MWANGAI E A HIST\u00d3RIA - GERSON PRATA -","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/ajustica.net\/index.php\/2024\/03\/13\/mwangai-e-a-historia-gerson-prata\/","og_locale":"pt_BR","og_type":"article","og_title":"MWANGAI E A HIST\u00d3RIA - GERSON PRATA -","og_description":"&nbsp;A hist\u00f3ria de verdade e da verdade n\u00e3o morre e n\u00e3o se apaga. E a verdade \u00e9 que existem localidades que, devido a sua import\u00e2ncia e simbolismo, est\u00e3o ligadas \u00e0 mem\u00f3ria colectiva de determinados povos ou grupos de pessoas que comungam do mesmo ide\u00e1rio Pol\u00edtico. \u00c9 agir de m\u00e1 f\u00e9 inventar artif\u00edcios para apagar essas [&hellip;]","og_url":"https:\/\/ajustica.net\/index.php\/2024\/03\/13\/mwangai-e-a-historia-gerson-prata\/","article_published_time":"2024-03-13T16:36:33+00:00","article_modified_time":"2024-03-13T16:36:34+00:00","og_image":[{"width":960,"height":720,"url":"https:\/\/ajustica.net\/wp-content\/uploads\/2024\/03\/jonasvalentim.jpg","type":"image\/jpeg"}],"author":"Portal Justi\u00e7a","twitter_card":"summary_large_image","twitter_misc":{"Escrito por":"Portal Justi\u00e7a","Est. tempo de leitura":"2 minutos"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"WebPage","@id":"https:\/\/ajustica.net\/index.php\/2024\/03\/13\/mwangai-e-a-historia-gerson-prata\/","url":"https:\/\/ajustica.net\/index.php\/2024\/03\/13\/mwangai-e-a-historia-gerson-prata\/","name":"MWANGAI E A HIST\u00d3RIA - GERSON PRATA -","isPartOf":{"@id":"https:\/\/ajustica.net\/#website"},"datePublished":"2024-03-13T16:36:33+00:00","dateModified":"2024-03-13T16:36:34+00:00","author":{"@id":"https:\/\/ajustica.net\/#\/schema\/person\/e1f71ed49e0f63898db2951a6b747d62"},"breadcrumb":{"@id":"https:\/\/ajustica.net\/index.php\/2024\/03\/13\/mwangai-e-a-historia-gerson-prata\/#breadcrumb"},"inLanguage":"pt-BR","potentialAction":[{"@type":"ReadAction","target":["https:\/\/ajustica.net\/index.php\/2024\/03\/13\/mwangai-e-a-historia-gerson-prata\/"]}]},{"@type":"BreadcrumbList","@id":"https:\/\/ajustica.net\/index.php\/2024\/03\/13\/mwangai-e-a-historia-gerson-prata\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"In\u00edcio","item":"https:\/\/ajustica.net\/"},{"@type":"ListItem","position":2,"name":"MWANGAI E A HIST\u00d3RIA &#8211; GERSON PRATA"}]},{"@type":"WebSite","@id":"https:\/\/ajustica.net\/#website","url":"https:\/\/ajustica.net\/","name":"","description":"Email Para Den\u00fancia: ajusticaa@gmail.com","potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/ajustica.net\/?s={search_term_string}"},"query-input":"required name=search_term_string"}],"inLanguage":"pt-BR"},{"@type":"Person","@id":"https:\/\/ajustica.net\/#\/schema\/person\/e1f71ed49e0f63898db2951a6b747d62","name":"Portal Justi\u00e7a","image":{"@type":"ImageObject","inLanguage":"pt-BR","@id":"https:\/\/ajustica.net\/#\/schema\/person\/image\/","url":"https:\/\/secure.gravatar.com\/avatar\/14c19bb3bbce6a73ddabbf74322a5807?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/14c19bb3bbce6a73ddabbf74322a5807?s=96&d=mm&r=g","caption":"Portal Justi\u00e7a"},"url":"https:\/\/ajustica.net\/index.php\/author\/justica\/"}]}},"_links":{"self":[{"href":"https:\/\/ajustica.net\/index.php\/wp-json\/wp\/v2\/posts\/1446"}],"collection":[{"href":"https:\/\/ajustica.net\/index.php\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/ajustica.net\/index.php\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/ajustica.net\/index.php\/wp-json\/wp\/v2\/users\/3"}],"replies":[{"embeddable":true,"href":"https:\/\/ajustica.net\/index.php\/wp-json\/wp\/v2\/comments?post=1446"}],"version-history":[{"count":1,"href":"https:\/\/ajustica.net\/index.php\/wp-json\/wp\/v2\/posts\/1446\/revisions"}],"predecessor-version":[{"id":1448,"href":"https:\/\/ajustica.net\/index.php\/wp-json\/wp\/v2\/posts\/1446\/revisions\/1448"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/ajustica.net\/index.php\/wp-json\/wp\/v2\/media\/1447"}],"wp:attachment":[{"href":"https:\/\/ajustica.net\/index.php\/wp-json\/wp\/v2\/media?parent=1446"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/ajustica.net\/index.php\/wp-json\/wp\/v2\/categories?post=1446"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/ajustica.net\/index.php\/wp-json\/wp\/v2\/tags?post=1446"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}